{"id":4674,"date":"2024-12-15T10:04:00","date_gmt":"2024-12-15T10:04:00","guid":{"rendered":"https:\/\/harborlondon.com\/?p=4674"},"modified":"2026-03-05T14:54:55","modified_gmt":"2026-03-05T14:54:55","slug":"%d8%a7%d9%86%d9%88%d8%a7%d8%b9-%d8%a7%d9%84%d8%a7%d8%b6%d8%b7%d8%b1%d8%a7%d8%a8%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9-%d9%88%d8%b9%d9%84%d8%a7%d8%ac%d9%87%d8%a7","status":"publish","type":"post","link":"https:\/\/harborlondon.com\/ar\/%d8%a7%d9%86%d9%88%d8%a7%d8%b9-%d8%a7%d9%84%d8%a7%d8%b6%d8%b7%d8%b1%d8%a7%d8%a8%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9-%d9%88%d8%b9%d9%84%d8%a7%d8%ac%d9%87%d8%a7\/","title":{"rendered":"\u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629 \u0648\u0639\u0644\u0627\u062c\u0647\u0627"},"content":{"rendered":"<style>.kadence-column4674_91fca7-40 > .kt-inside-inner-col,.kadence-column4674_91fca7-40 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4674_91fca7-40 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4674_91fca7-40 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4674_91fca7-40 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4674_91fca7-40 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4674_91fca7-40{position:relative;}@media all and (max-width: 1024px){.kadence-column4674_91fca7-40 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4674_91fca7-40 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4674_91fca7-40 main_post_content_wrap\"><div class=\"kt-inside-inner-col\"><style>.kadence-column4674_57701e-7e > .kt-inside-inner-col,.kadence-column4674_57701e-7e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4674_57701e-7e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4674_57701e-7e > .kt-inside-inner-col{flex-direction:column;}.kadence-column4674_57701e-7e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4674_57701e-7e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4674_57701e-7e{position:relative;}.kadence-column4674_57701e-7e, .kt-inside-inner-col > .kadence-column4674_57701e-7e:not(.specificity){margin-bottom:80px;}@media all and (max-width: 1024px){.kadence-column4674_57701e-7e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column4674_57701e-7e, .kt-inside-inner-col > .kadence-column4674_57701e-7e:not(.specificity){margin-bottom:60px;}}@media all and (max-width: 767px){.kadence-column4674_57701e-7e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4674_57701e-7e table_content_scrolled_sec single_article_single_content_section\" id=\"section_id3\"><div class=\"kt-inside-inner-col\"><style>.kadence-column4674_47d674-a2 > .kt-inside-inner-col,.kadence-column4674_47d674-a2 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4674_47d674-a2 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4674_47d674-a2 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4674_47d674-a2 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4674_47d674-a2 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4674_47d674-a2{position:relative;}@media all and (max-width: 1024px){.kadence-column4674_47d674-a2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4674_47d674-a2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4674_47d674-a2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4674_918b29-9f, .wp-block-kadence-advancedheading.kt-adv-heading4674_918b29-9f[data-kb-block=\"kb-adv-heading4674_918b29-9f\"]{margin-bottom:25px;font-style:normal;border-bottom:0px solid var(--global-palette6, #718096);}.wp-block-kadence-advancedheading.kt-adv-heading4674_918b29-9f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4674_918b29-9f[data-kb-block=\"kb-adv-heading4674_918b29-9f\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4674_918b29-9f img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4674_918b29-9f[data-kb-block=\"kb-adv-heading4674_918b29-9f\"] img.kb-inline-image{width:150px;vertical-align:baseline;}.wp-block-kadence-advancedheading.kt-adv-heading4674_918b29-9f[data-kb-block=\"kb-adv-heading4674_918b29-9f\"] a, .kt-adv-heading-link4674_918b29-9f, .kt-adv-heading-link4674_918b29-9f .kt-adv-heading4674_918b29-9f[data-kb-block=\"kb-adv-heading4674_918b29-9f\"]{color:var(--global-palette3, #1A202C);}.wp-block-kadence-advancedheading.kt-adv-heading4674_918b29-9f[data-kb-block=\"kb-adv-heading4674_918b29-9f\"] a:hover, .kt-adv-heading-link4674_918b29-9f:hover, .kt-adv-heading-link4674_918b29-9f:hover .kt-adv-heading4674_918b29-9f[data-kb-block=\"kb-adv-heading4674_918b29-9f\"]{color:var(--global-palette3, #1A202C);}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading4674_918b29-9f, .wp-block-kadence-advancedheading.kt-adv-heading4674_918b29-9f[data-kb-block=\"kb-adv-heading4674_918b29-9f\"]{border-bottom:0px solid var(--global-palette6, #718096);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4674_918b29-9f, .wp-block-kadence-advancedheading.kt-adv-heading4674_918b29-9f[data-kb-block=\"kb-adv-heading4674_918b29-9f\"]{border-bottom:0px solid var(--global-palette6, #718096);}}<\/style>\n<p class=\"kt-adv-heading4674_918b29-9f wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4674_918b29-9f\">\u0628\u0630\u0644 \u0639\u0644\u0645\u0627\u0621 \u0627\u0644\u0646\u0641\u0633 \u0627\u0644\u0643\u062b\u064a\u0631 \u0645\u0646 \u0627\u0644\u0648\u0642\u062a \u0648\u0627\u0644\u062c\u0647\u062f \u0639\u0644\u0649 \u0645\u062f\u0627\u0631 \u0627\u0644\u0633\u0646\u0648\u0627\u062a \u0627\u0644\u0633\u0627\u0628\u0642\u0629 \u0644\u0644\u062a\u0639\u0631\u0641 \u0639\u0644\u0649 \u062e\u0641\u0627\u064a\u0627 \u0627\u0644\u0646\u0641\u0633 \u0627\u0644\u0628\u0634\u0631\u064a\u0629\u061b \u0630\u0644\u0643 \u0623\u0646 \u0641\u0647\u0645 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629 \u0648\u0639\u0644\u0627\u062c\u0647\u0627 \u0645\u0639\u0642\u062f \u0648\u064a\u062d\u062a\u0627\u062c \u0627\u0644\u0649 \u0627\u0644\u0625\u0644\u0645\u0627\u0645 \u0628\u062c\u0645\u064a\u0639 \u0627\u0644\u0638\u0631\u0648\u0641 \u0627\u0644\u062a\u064a \u062a\u0639\u0631\u0636 \u0644\u0647\u0627 \u0627\u0644\u0634\u062e\u0635 \u0627\u0644\u0645\u0635\u0627\u0628 \u0628\u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628 \u0627\u0644\u0646\u0641\u0633\u064a\u060c \u0644\u064a\u0633\u062a \u0627\u0644\u0638\u0631\u0648\u0641 \u0627\u0644\u062d\u0627\u0644\u064a\u0629 \u0641\u0642\u0637 \u0648\u0627\u0646\u0645\u0627 \u062a\u0635\u0644 \u0627\u0644\u062d\u0627\u062c\u0629 \u0644\u0645\u0639\u0631\u0641\u0629 \u0638\u0631\u0648\u0641 \u0627\u0644\u0646\u0634\u0623\u0629 \u0627\u0644\u062d\u064a\u0627\u062a\u064a\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0634\u062e\u0635\u061b \u0648\u0645\u0639\u0631\u0641\u0629 \u0637\u0628\u064a\u0639\u0629 \u0634\u062e\u0635\u064a\u062a\u0647 \u061b\u0648\u0643\u0644\u0645\u0627 \u0643\u0627\u0646\u062a \u0627\u0644\u0645\u0639\u0644\u0648\u0645\u0627\u062a \u0648\u0641\u064a\u0631\u0629 \u0643\u0627\u0646 \u0627\u0644\u062a\u0634\u062e\u064a\u0635 \u0623\u062f\u0642 \u0648\u0623\u0642\u0631\u0628 \u0625\u0644\u0649 \u0627\u0644\u0635\u062d\u0629. \u0641\u064a \u0647\u0630\u0647 \u0627\u0644\u0645\u062f\u0648\u0646\u0629 \u0633\u0648\u0641 \u0646\u0639\u0631\u0636 \u0623\u0647\u0645 \u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u0623\u0645\u0631\u0627\u0636 \u0627\u0644\u0646\u0641\u0633\u064a\u0629 \u0648\u0623\u0647\u0645 \u0627\u0644\u0645\u0639\u0644\u0648\u0645\u0627\u062a \u0639\u0646 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628 \u0627\u0644\u0646\u0641\u0633\u064a\u060c \u0623\u0639\u0631\u0627\u0636\u0647 \u0648\u0623\u0633\u0628\u0627\u0628\u0647 \u0648\u0637\u0631\u0642 \u0639\u0644\u0627\u062c\u0647.<\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column4674_acb890-d0 > .kt-inside-inner-col,.kadence-column4674_acb890-d0 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4674_acb890-d0 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4674_acb890-d0 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4674_acb890-d0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4674_acb890-d0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4674_acb890-d0{position:relative;}.kadence-column4674_acb890-d0, .kt-inside-inner-col > .kadence-column4674_acb890-d0:not(.specificity){margin-bottom:80px;}@media all and (max-width: 1024px){.kadence-column4674_acb890-d0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column4674_acb890-d0, .kt-inside-inner-col > .kadence-column4674_acb890-d0:not(.specificity){margin-bottom:60px;}}@media all and (max-width: 767px){.kadence-column4674_acb890-d0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4674_acb890-d0 single_article_single_content_section\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4674_a5a975-25, .wp-block-kadence-advancedheading.kt-adv-heading4674_a5a975-25[data-kb-block=\"kb-adv-heading4674_a5a975-25\"]{margin-bottom:32px;font-size:32px;line-height:41px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4674_a5a975-25 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4674_a5a975-25[data-kb-block=\"kb-adv-heading4674_a5a975-25\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4674_a5a975-25 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4674_a5a975-25[data-kb-block=\"kb-adv-heading4674_a5a975-25\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4674_a5a975-25, .wp-block-kadence-advancedheading.kt-adv-heading4674_a5a975-25[data-kb-block=\"kb-adv-heading4674_a5a975-25\"]{margin-bottom:24px;font-size:24px;line-height:29px;}}<\/style>\n<h2 class=\"kt-adv-heading4674_a5a975-25 heading_h3 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4674_a5a975-25\">\u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629<\/h2>\n\n\n<style>.kadence-column4674_60fbb9-0b > .kt-inside-inner-col,.kadence-column4674_60fbb9-0b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4674_60fbb9-0b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4674_60fbb9-0b > .kt-inside-inner-col{flex-direction:column;}.kadence-column4674_60fbb9-0b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4674_60fbb9-0b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4674_60fbb9-0b{position:relative;}@media all and (max-width: 1024px){.kadence-column4674_60fbb9-0b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4674_60fbb9-0b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4674_60fbb9-0b\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4674_def5f7-62, .wp-block-kadence-advancedheading.kt-adv-heading4674_def5f7-62[data-kb-block=\"kb-adv-heading4674_def5f7-62\"]{margin-bottom:25px;font-style:normal;border-bottom:0px solid var(--global-palette6, #718096);}.wp-block-kadence-advancedheading.kt-adv-heading4674_def5f7-62 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4674_def5f7-62[data-kb-block=\"kb-adv-heading4674_def5f7-62\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4674_def5f7-62 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4674_def5f7-62[data-kb-block=\"kb-adv-heading4674_def5f7-62\"] img.kb-inline-image{width:150px;vertical-align:baseline;}.wp-block-kadence-advancedheading.kt-adv-heading4674_def5f7-62[data-kb-block=\"kb-adv-heading4674_def5f7-62\"] a, .kt-adv-heading-link4674_def5f7-62, .kt-adv-heading-link4674_def5f7-62 .kt-adv-heading4674_def5f7-62[data-kb-block=\"kb-adv-heading4674_def5f7-62\"]{color:var(--global-palette3, #1A202C);}.wp-block-kadence-advancedheading.kt-adv-heading4674_def5f7-62[data-kb-block=\"kb-adv-heading4674_def5f7-62\"] a:hover, .kt-adv-heading-link4674_def5f7-62:hover, .kt-adv-heading-link4674_def5f7-62:hover .kt-adv-heading4674_def5f7-62[data-kb-block=\"kb-adv-heading4674_def5f7-62\"]{color:var(--global-palette3, #1A202C);}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading4674_def5f7-62, .wp-block-kadence-advancedheading.kt-adv-heading4674_def5f7-62[data-kb-block=\"kb-adv-heading4674_def5f7-62\"]{border-bottom:0px solid var(--global-palette6, #718096);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4674_def5f7-62, .wp-block-kadence-advancedheading.kt-adv-heading4674_def5f7-62[data-kb-block=\"kb-adv-heading4674_def5f7-62\"]{border-bottom:0px solid var(--global-palette6, #718096);}}<\/style>\n<p class=\"kt-adv-heading4674_def5f7-62 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4674_def5f7-62\">\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u0623\u0645\u0631\u0627\u0636 \u0627\u0644\u0646\u0641\u0633\u064a\u0629\u060c \u0645\u0646\u0647\u0627 \u0645\u0627 \u0647\u0648 \u0634\u0627\u0626\u0639 \u0648\u0644\u0647 \u0623\u0639\u0631\u0627\u0636 \u0645\u0639\u0631\u0648\u0641\u0629\u060c \u0648\u0645\u0646\u0647\u0627 \u0645\u0627 \u0647\u0648 \u0646\u0627\u062f\u0631 \u0648\u0644\u0627 \u064a\u0639\u0631\u0641 \u0639\u0646\u0647 \u0627\u0644\u0643\u062b\u064a\u0631 \u0645\u0646 \u0627\u0644\u0646\u0627\u0633\u060c \u0648\u0645\u0646 \u0623\u0634\u0647\u0631 \u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u0623\u0645\u0631\u0627\u0636 \u0627\u0644\u0646\u0641\u0633\u064a\u0629 \u0645\u0627 \u064a\u0644\u064a:<\/p>\n<\/div><\/div>\n\n\n<style>.kt-accordion-id4674_a76048-24 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:10px;}.kt-accordion-id4674_a76048-24 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;background:var(--global-palette8, #F7FAFC);padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;}.kt-accordion-id4674_a76048-24 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #949494;border-right:0px solid #949494;border-bottom:1px solid var(--global-palette6, #718096);border-left:0px solid #949494;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:var(--global-palette8, #F7FAFC);font-size:25px;line-height:33px;color:var(--global-palette3, #1A202C);padding-top:30px;padding-right:20px;padding-bottom:30px;padding-left:20px;}.kt-accordion-id4674_a76048-24:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id4674_a76048-24:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette3, #1A202C);}.kt-accordion-id4674_a76048-24 .kt-accordion-panel-inner, .kt-accordion-id4674_a76048-24 .kt-accordion-panel-inner h1, .kt-accordion-id4674_a76048-24 .kt-accordion-panel-inner h2, .kt-accordion-id4674_a76048-24 .kt-accordion-panel-inner h3, .kt-accordion-id4674_a76048-24 .kt-accordion-panel-inner h4, .kt-accordion-id4674_a76048-24 .kt-accordion-panel-inner h5, .kt-accordion-id4674_a76048-24 .kt-accordion-panel-inner h6{color:var(--global-palette3, #1A202C);}.kt-accordion-id4674_a76048-24:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:var(--global-palette3, #1A202C);}.kt-accordion-id4674_a76048-24:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id4674_a76048-24:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette8, #F7FAFC);}.kt-accordion-id4674_a76048-24 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id4674_a76048-24 .kt-blocks-accordion-header:focus-visible{color:var(--global-palette3, #1A202C);background:var(--global-palette8, #F7FAFC);border-top-color:var(--global-palette3, #1A202C);border-top-style:solid;border-right-color:var(--global-palette3, #1A202C);border-right-style:solid;border-bottom:1px solid var(--global-palette3, #1A202C);border-left-color:var(--global-palette3, #1A202C);border-left-style:solid;}.kt-accordion-id4674_a76048-24:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id4674_a76048-24:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id4674_a76048-24:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id4674_a76048-24:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette3, #1A202C);}.kt-accordion-id4674_a76048-24:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id4674_a76048-24:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:var(--global-palette3, #1A202C);}.kt-accordion-id4674_a76048-24:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id4674_a76048-24:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id4674_a76048-24:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id4674_a76048-24:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette8, #F7FAFC);}.kt-accordion-id4674_a76048-24 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id4674_a76048-24 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:var(--global-palette3, #1A202C);background:var(--global-palette8, #F7FAFC);border-top-color:var(--global-palette3, #1A202C);border-top-style:solid;border-right-color:var(--global-palette3, #1A202C);border-right-style:solid;border-bottom:1px solid var(--global-palette3, #1A202C);border-left-color:var(--global-palette3, #1A202C);border-left-style:solid;}.kt-accordion-id4674_a76048-24:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id4674_a76048-24:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette3, #1A202C);}.kt-accordion-id4674_a76048-24:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:var(--global-palette3, #1A202C);}.kt-accordion-id4674_a76048-24:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id4674_a76048-24:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:var(--global-palette8, #F7FAFC);}@media all and (max-width: 1024px){.kt-accordion-id4674_a76048-24 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id4674_a76048-24 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #949494;border-right:0px solid #949494;border-bottom:1px solid var(--global-palette6, #718096);border-left:0px solid #949494;}}@media all and (max-width: 1024px){.kt-accordion-id4674_a76048-24 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id4674_a76048-24 .kt-blocks-accordion-header:focus-visible{border-top-color:var(--global-palette3, #1A202C);border-top-style:solid;border-right-color:var(--global-palette3, #1A202C);border-right-style:solid;border-bottom:1px solid var(--global-palette3, #1A202C);border-left-color:var(--global-palette3, #1A202C);border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id4674_a76048-24 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id4674_a76048-24 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:var(--global-palette3, #1A202C);border-top-style:solid;border-right-color:var(--global-palette3, #1A202C);border-right-style:solid;border-bottom:1px solid var(--global-palette3, #1A202C);border-left-color:var(--global-palette3, #1A202C);border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id4674_a76048-24 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id4674_a76048-24 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:10px;}.kt-accordion-id4674_a76048-24 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;padding-right:0px;padding-left:0px;}.kt-accordion-id4674_a76048-24 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:0px solid #949494;border-right:0px solid #949494;border-bottom:1px solid var(--global-palette6, #718096);border-left:0px solid #949494;font-size:18px;line-height:24px;padding-right:0px;padding-left:0px;}.kt-accordion-id4674_a76048-24 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id4674_a76048-24 .kt-blocks-accordion-header:focus-visible{border-top-color:var(--global-palette3, #1A202C);border-top-style:solid;border-right-color:var(--global-palette3, #1A202C);border-right-style:solid;border-bottom:1px solid var(--global-palette3, #1A202C);border-left-color:var(--global-palette3, #1A202C);border-left-style:solid;}.kt-accordion-id4674_a76048-24 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id4674_a76048-24 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:var(--global-palette3, #1A202C);border-top-style:solid;border-right-color:var(--global-palette3, #1A202C);border-right-style:solid;border-bottom:1px solid var(--global-palette3, #1A202C);border-left-color:var(--global-palette3, #1A202C);border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id4674_a76048-24 kt-accordion-has-9-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-xclose kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-1 kt-pane4674_141644-cb\"><h4 class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628 \u062b\u0646\u0627\u0626\u064a \u0627\u0644\u0642\u0637\u0628<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/h4><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.kadence-column4674_201c98-e2 > .kt-inside-inner-col,.kadence-column4674_201c98-e2 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4674_201c98-e2 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4674_201c98-e2 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4674_201c98-e2 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4674_201c98-e2 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4674_201c98-e2{position:relative;}@media all and (max-width: 1024px){.kadence-column4674_201c98-e2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4674_201c98-e2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4674_201c98-e2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4674_dab2a4-24, .wp-block-kadence-advancedheading.kt-adv-heading4674_dab2a4-24[data-kb-block=\"kb-adv-heading4674_dab2a4-24\"]{margin-bottom:0px;font-style:normal;border-bottom:0px solid var(--global-palette6, #718096);}.wp-block-kadence-advancedheading.kt-adv-heading4674_dab2a4-24 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4674_dab2a4-24[data-kb-block=\"kb-adv-heading4674_dab2a4-24\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4674_dab2a4-24 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4674_dab2a4-24[data-kb-block=\"kb-adv-heading4674_dab2a4-24\"] img.kb-inline-image{width:150px;vertical-align:baseline;}.wp-block-kadence-advancedheading.kt-adv-heading4674_dab2a4-24[data-kb-block=\"kb-adv-heading4674_dab2a4-24\"] a, .kt-adv-heading-link4674_dab2a4-24, .kt-adv-heading-link4674_dab2a4-24 .kt-adv-heading4674_dab2a4-24[data-kb-block=\"kb-adv-heading4674_dab2a4-24\"]{color:var(--global-palette3, #1A202C);}.wp-block-kadence-advancedheading.kt-adv-heading4674_dab2a4-24[data-kb-block=\"kb-adv-heading4674_dab2a4-24\"] a:hover, .kt-adv-heading-link4674_dab2a4-24:hover, .kt-adv-heading-link4674_dab2a4-24:hover .kt-adv-heading4674_dab2a4-24[data-kb-block=\"kb-adv-heading4674_dab2a4-24\"]{color:var(--global-palette3, #1A202C);}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading4674_dab2a4-24, .wp-block-kadence-advancedheading.kt-adv-heading4674_dab2a4-24[data-kb-block=\"kb-adv-heading4674_dab2a4-24\"]{border-bottom:0px solid var(--global-palette6, #718096);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4674_dab2a4-24, .wp-block-kadence-advancedheading.kt-adv-heading4674_dab2a4-24[data-kb-block=\"kb-adv-heading4674_dab2a4-24\"]{border-bottom:0px solid var(--global-palette6, #718096);}}<\/style>\n<p class=\"kt-adv-heading4674_dab2a4-24 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4674_dab2a4-24\">\u0641\u064a\u0647 \u064a\u062a\u0623\u0631\u062c\u062d \u0627\u0644\u0645\u0631\u064a\u0636 \u0628\u064a\u0646 \u0646\u0648\u0628\u0627\u062a \u0627\u0643\u062a\u0626\u0627\u0628 \u0648\u0628\u064a\u0646 \u0646\u0648\u0628\u0627\u062a \u0647\u0648\u0633 \u0623\u0648 \u0627\u0633\u062a\u062b\u0627\u0631\u0629 \u0645\u0641\u0631\u0637\u0629 \u0648\u0646\u0634\u0627\u0637 \u0632\u0627\u0626\u062f \u0628\u0627\u0644\u062a\u0628\u0627\u062f\u0644\u060c \u0648\u0645\u062f\u0629 \u0646\u0648\u0628\u0629 \u0627\u0644\u0627\u0643\u062a\u0626\u0627\u0628 \u0623\u0648 \u0646\u0648\u0628\u0629 \u0627\u0644\u0647\u0648\u0633 \u062a\u062e\u062a\u0644\u0641 \u0645\u0646 \u0634\u062e\u0635 \u0644\u0622\u062e\u0631\u061b \u0641\u0628\u0639\u0636 \u0627\u0644\u0623\u0634\u062e\u0627\u0635 \u0627\u0644\u0645\u0635\u0627\u0628\u064a\u0646 \u0628\u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628 \u062b\u0646\u0627\u0626\u064a \u0627\u0644\u0642\u0637\u0628 \u062a\u0643\u0648\u0646 \u0627\u0644\u0646\u0648\u0628\u0627\u062a \u0639\u0646\u062f\u0647\u0645 \u0642\u0635\u064a\u0631\u0629 \u0644\u0639\u062f\u0629 \u0623\u064a\u0627\u0645 \u0623\u0648 \u0639\u062f\u0629 \u0634\u0647\u0648\u0631\u060c \u0648\u0627\u0644\u0628\u0639\u0636 \u0627\u0644\u0622\u062e\u0631 \u0645\u062f\u0629 \u0627\u0644\u0646\u0648\u0628\u0629\u00a0 \u0642\u062f \u062a\u0635\u0644 \u0625\u0644\u0649 \u0633\u0646\u0648\u0627\u062a.<\/p>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-2 kt-pane4674_ecc02e-9c\"><h4 class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u0627\u0646\u0641\u0635\u0627\u0645 \u0627\u0644\u0634\u062e\u0635\u064a\u0629 \u0648\u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0645\u0635\u0627\u062d\u0628\u0629<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/h4><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.kadence-column4674_e77fd3-2a > .kt-inside-inner-col,.kadence-column4674_e77fd3-2a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4674_e77fd3-2a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4674_e77fd3-2a > .kt-inside-inner-col{flex-direction:column;}.kadence-column4674_e77fd3-2a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4674_e77fd3-2a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4674_e77fd3-2a{position:relative;}@media all and (max-width: 1024px){.kadence-column4674_e77fd3-2a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4674_e77fd3-2a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4674_e77fd3-2a\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4674_44d6bd-36, .wp-block-kadence-advancedheading.kt-adv-heading4674_44d6bd-36[data-kb-block=\"kb-adv-heading4674_44d6bd-36\"]{margin-bottom:0px;font-style:normal;border-bottom:0px solid var(--global-palette6, #718096);}.wp-block-kadence-advancedheading.kt-adv-heading4674_44d6bd-36 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4674_44d6bd-36[data-kb-block=\"kb-adv-heading4674_44d6bd-36\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4674_44d6bd-36 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4674_44d6bd-36[data-kb-block=\"kb-adv-heading4674_44d6bd-36\"] img.kb-inline-image{width:150px;vertical-align:baseline;}.wp-block-kadence-advancedheading.kt-adv-heading4674_44d6bd-36[data-kb-block=\"kb-adv-heading4674_44d6bd-36\"] a, .kt-adv-heading-link4674_44d6bd-36, .kt-adv-heading-link4674_44d6bd-36 .kt-adv-heading4674_44d6bd-36[data-kb-block=\"kb-adv-heading4674_44d6bd-36\"]{color:var(--global-palette3, #1A202C);}.wp-block-kadence-advancedheading.kt-adv-heading4674_44d6bd-36[data-kb-block=\"kb-adv-heading4674_44d6bd-36\"] a:hover, .kt-adv-heading-link4674_44d6bd-36:hover, .kt-adv-heading-link4674_44d6bd-36:hover .kt-adv-heading4674_44d6bd-36[data-kb-block=\"kb-adv-heading4674_44d6bd-36\"]{color:var(--global-palette3, #1A202C);}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading4674_44d6bd-36, .wp-block-kadence-advancedheading.kt-adv-heading4674_44d6bd-36[data-kb-block=\"kb-adv-heading4674_44d6bd-36\"]{border-bottom:0px solid var(--global-palette6, #718096);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4674_44d6bd-36, .wp-block-kadence-advancedheading.kt-adv-heading4674_44d6bd-36[data-kb-block=\"kb-adv-heading4674_44d6bd-36\"]{border-bottom:0px solid var(--global-palette6, #718096);}}<\/style>\n<p class=\"kt-adv-heading4674_44d6bd-36 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4674_44d6bd-36\">\u064a\u0639\u0627\u0646\u064a \u0627\u0644\u0645\u0635\u0627\u0628\u0648\u0646 \u0628\u0645\u0631\u0636 \u0627\u0646\u0641\u0635\u0627\u0645 \u0627\u0644\u0634\u062e\u0635\u064a\u0629 (Schizophrenia) \u0645\u0646 \u0627\u0644\u0627\u0646\u0641\u0635\u0627\u0644 \u0639\u0646 \u0627\u0644\u0648\u0627\u0642\u0639 \u0648\u062d\u062f\u0648\u062b \u0636\u0644\u0627\u0644\u0627\u062a \u0648\u0647\u0644\u0627\u0648\u0633 \u0633\u0645\u0639\u064a\u0629 \u0648\u0628\u0635\u0631\u064a\u0629\u060c\u00a0\u0643\u0630\u0644\u0643 \u064a\u062d\u062f\u062b \u062a\u0634\u0648\u0634 \u0641\u064a \u0627\u0644\u0623\u0641\u0643\u0627\u0631 \u0648\u064a\u0643\u0648\u0646 \u062d\u062f\u064a\u062b\u0647 \u063a\u064a\u0631 \u0645\u0646\u0638\u0645 \u0648\u063a\u064a\u0631 \u0645\u062a\u0631\u0627\u0628\u0637.<\/p>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-3 kt-pane4674_6218aa-1a\"><h4 class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0627\u0643\u062a\u0626\u0627\u0628\u064a\u0629<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/h4><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.kadence-column4674_7e5741-21 > .kt-inside-inner-col,.kadence-column4674_7e5741-21 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4674_7e5741-21 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4674_7e5741-21 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4674_7e5741-21 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4674_7e5741-21 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4674_7e5741-21{position:relative;}@media all and (max-width: 1024px){.kadence-column4674_7e5741-21 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4674_7e5741-21 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4674_7e5741-21\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4674_84bd5a-7b, .wp-block-kadence-advancedheading.kt-adv-heading4674_84bd5a-7b[data-kb-block=\"kb-adv-heading4674_84bd5a-7b\"]{margin-bottom:0px;font-style:normal;border-bottom:0px solid var(--global-palette6, #718096);}.wp-block-kadence-advancedheading.kt-adv-heading4674_84bd5a-7b mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4674_84bd5a-7b[data-kb-block=\"kb-adv-heading4674_84bd5a-7b\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4674_84bd5a-7b img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4674_84bd5a-7b[data-kb-block=\"kb-adv-heading4674_84bd5a-7b\"] img.kb-inline-image{width:150px;vertical-align:baseline;}.wp-block-kadence-advancedheading.kt-adv-heading4674_84bd5a-7b[data-kb-block=\"kb-adv-heading4674_84bd5a-7b\"] a, .kt-adv-heading-link4674_84bd5a-7b, .kt-adv-heading-link4674_84bd5a-7b .kt-adv-heading4674_84bd5a-7b[data-kb-block=\"kb-adv-heading4674_84bd5a-7b\"]{color:var(--global-palette3, #1A202C);}.wp-block-kadence-advancedheading.kt-adv-heading4674_84bd5a-7b[data-kb-block=\"kb-adv-heading4674_84bd5a-7b\"] a:hover, .kt-adv-heading-link4674_84bd5a-7b:hover, .kt-adv-heading-link4674_84bd5a-7b:hover .kt-adv-heading4674_84bd5a-7b[data-kb-block=\"kb-adv-heading4674_84bd5a-7b\"]{color:var(--global-palette3, #1A202C);}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading4674_84bd5a-7b, .wp-block-kadence-advancedheading.kt-adv-heading4674_84bd5a-7b[data-kb-block=\"kb-adv-heading4674_84bd5a-7b\"]{border-bottom:0px solid var(--global-palette6, #718096);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4674_84bd5a-7b, .wp-block-kadence-advancedheading.kt-adv-heading4674_84bd5a-7b[data-kb-block=\"kb-adv-heading4674_84bd5a-7b\"]{border-bottom:0px solid var(--global-palette6, #718096);}}<\/style>\n<p class=\"kt-adv-heading4674_84bd5a-7b wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4674_84bd5a-7b\">\u064a\u0639\u062f \u0627\u0644\u0627\u0643\u062a\u0626\u0627\u0628 \u0645\u0646 \u0623\u0634\u0647\u0631 \u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629 \u0627\u0644\u062a\u064a \u064a\u0633\u062a\u0644\u0632\u0645 \u0639\u0644\u0627\u062c\u0647\u0627 \u0645\u062f\u0629 \u0637\u0648\u064a\u0644\u0629 \u0642\u062f \u062a\u0635\u0644 \u0625\u0644\u0649 \u0634\u0647\u0648\u0631 \u0648\u0633\u0646\u0648\u0627\u062a\u060c \u0648\u0641\u064a\u0647\u0627 \u064a\u0639\u0627\u0646\u064a \u0627\u0644\u0634\u062e\u0635 \u0645\u0646 \u0634\u0639\u0648\u0631 \u062f\u0627\u0626\u0645 \u0628\u0627\u0644\u062d\u0632\u0646 \u0648\u0641\u0642\u062f\u0627\u0646 \u0627\u0644\u0631\u063a\u0628\u0629 \u0641\u064a \u0627\u0644\u062d\u064a\u0627\u0629 \u0648\u0639\u062f\u0645 \u0627\u0644\u0625\u062d\u0633\u0627\u0633\u00a0 \u0628\u0642\u064a\u0645\u0629 \u0627\u0644\u0623\u0634\u064a\u0627\u0621\u060c \u0628\u0627\u0644\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0627\u0644\u0625\u062d\u0633\u0627\u0633 \u0628\u0627\u0644\u0644\u0627\u0645\u0628\u0627\u0644\u0627\u0629 \u062a\u062c\u0627\u0647 \u0627\u0644\u0623\u062d\u062f\u0627\u062b \u0627\u0644\u0645\u062d\u064a\u0637\u0629\u060c \u0643\u0645\u0627 \u064a\u0646\u0639\u062f\u0645 \u0641\u064a\u0647\u0627 \u0634\u0639\u0648\u0631 \u0627\u0644\u0625\u0646\u0633\u0627\u0646 \u0628\u0623\u0647\u0645\u064a\u062a\u0647 \u0627\u0644\u0630\u0627\u062a\u064a\u0629.<\/p>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-4 kt-pane4674_d4e3c2-6b\"><h4 class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0642\u0644\u0642<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/h4><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.kadence-column4674_0a2b46-d7 > .kt-inside-inner-col,.kadence-column4674_0a2b46-d7 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4674_0a2b46-d7 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4674_0a2b46-d7 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4674_0a2b46-d7 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4674_0a2b46-d7 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4674_0a2b46-d7{position:relative;}@media all and (max-width: 1024px){.kadence-column4674_0a2b46-d7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4674_0a2b46-d7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4674_0a2b46-d7\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4674_a1252a-5b, .wp-block-kadence-advancedheading.kt-adv-heading4674_a1252a-5b[data-kb-block=\"kb-adv-heading4674_a1252a-5b\"]{font-style:normal;border-bottom:0px solid var(--global-palette6, #718096);}.wp-block-kadence-advancedheading.kt-adv-heading4674_a1252a-5b mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4674_a1252a-5b[data-kb-block=\"kb-adv-heading4674_a1252a-5b\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4674_a1252a-5b img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4674_a1252a-5b[data-kb-block=\"kb-adv-heading4674_a1252a-5b\"] img.kb-inline-image{width:150px;vertical-align:baseline;}.wp-block-kadence-advancedheading.kt-adv-heading4674_a1252a-5b[data-kb-block=\"kb-adv-heading4674_a1252a-5b\"] a, .kt-adv-heading-link4674_a1252a-5b, .kt-adv-heading-link4674_a1252a-5b .kt-adv-heading4674_a1252a-5b[data-kb-block=\"kb-adv-heading4674_a1252a-5b\"]{color:var(--global-palette3, #1A202C);}.wp-block-kadence-advancedheading.kt-adv-heading4674_a1252a-5b[data-kb-block=\"kb-adv-heading4674_a1252a-5b\"] a:hover, .kt-adv-heading-link4674_a1252a-5b:hover, .kt-adv-heading-link4674_a1252a-5b:hover .kt-adv-heading4674_a1252a-5b[data-kb-block=\"kb-adv-heading4674_a1252a-5b\"]{color:var(--global-palette3, #1A202C);}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading4674_a1252a-5b, .wp-block-kadence-advancedheading.kt-adv-heading4674_a1252a-5b[data-kb-block=\"kb-adv-heading4674_a1252a-5b\"]{border-bottom:0px solid var(--global-palette6, #718096);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4674_a1252a-5b, .wp-block-kadence-advancedheading.kt-adv-heading4674_a1252a-5b[data-kb-block=\"kb-adv-heading4674_a1252a-5b\"]{border-bottom:0px solid var(--global-palette6, #718096);}}<\/style>\n<p class=\"kt-adv-heading4674_a1252a-5b wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4674_a1252a-5b\">\u0627\u0644\u0642\u0644\u0642 \u0634\u0639\u0648\u0631 \u0637\u0628\u064a\u0639\u064a \u0644\u062f\u0649 \u0627\u0644\u0628\u0634\u0631 \u0628\u0648\u062c\u0647 \u0639\u0627\u0645\u061b \u0644\u0643\u0646\u0647 \u064a\u062a\u062d\u0648\u0644 \u0641\u064a \u0628\u0639\u0636 \u0627\u0644\u0623\u062d\u064a\u0627\u0646 \u0625\u0644\u0649 \u062d\u0627\u0644\u0629 \u0645\u0631\u0636\u064a\u0629 \u0639\u0646\u062f\u0645\u0627 \u064a\u0633\u064a\u0637\u0631 \u0639\u0644\u0649 \u062a\u0641\u0643\u064a\u0631 \u0627\u0644\u0634\u062e\u0635 \u0641\u064a \u062c\u0645\u064a\u0639 \u0645\u062d\u0627\u0648\u0631 \u062d\u064a\u0627\u062a\u0647 \u0648\u064a\u0624\u062b\u0631 \u0639\u0644\u0649 \u0642\u0631\u0627\u0631\u0627\u062a\u0647\u060c \u0648\u0643\u0645\u062b\u0627\u0644 \u0639\u0644\u0649 \u0630\u0644\u0643 \u062e\u0648\u0641 \u0628\u0639\u0636 \u0627\u0644\u0623\u0634\u062e\u0627\u0635 \u0645\u0646 \u0627\u0644\u0645\u0633\u062a\u0642\u0628\u0644 \u0648\u0645\u0627 \u0633\u064a\u062d\u0636\u0631\u0647 \u0645\u0646 \u0645\u0641\u0627\u062c\u0626\u0627\u062a \u0645\u0627 \u064a\u0636\u0637\u0631 \u0627\u0644\u0634\u062e\u0635 \u0627\u0644\u0630\u064a \u064a\u0639\u0627\u0646\u064a \u0645\u0646 \u0627\u0644\u0642\u0644\u0642 \u0625\u0644\u0649 \u0627\u0644\u062a\u0631\u062f\u062f \u0627\u0644\u062f\u0627\u0626\u0645 \u0641\u064a \u0627\u062a\u062e\u0627\u0630 \u0642\u0631\u0627\u0631\u0627\u062a\u0647 \u0648 \u0625\u0639\u0627\u0642\u0629 \u0623\u064a \u062a\u0642\u062f\u0645 \u0642\u062f \u064a\u062d\u062f\u062b \u0644\u0647 \u0641\u064a \u062d\u064a\u0627\u062a\u0647.<\/p>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-5 kt-pane4674_9d4f48-6e\"><h4 class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0648\u0633\u0648\u0627\u0633 \u0627\u0644\u0642\u0647\u0631\u064a<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/h4><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.kadence-column4674_36bff5-61 > .kt-inside-inner-col,.kadence-column4674_36bff5-61 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4674_36bff5-61 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4674_36bff5-61 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4674_36bff5-61 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4674_36bff5-61 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4674_36bff5-61{position:relative;}@media all and (max-width: 1024px){.kadence-column4674_36bff5-61 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4674_36bff5-61 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4674_36bff5-61\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4674_84dc8e-f7, .wp-block-kadence-advancedheading.kt-adv-heading4674_84dc8e-f7[data-kb-block=\"kb-adv-heading4674_84dc8e-f7\"]{margin-bottom:0px;font-style:normal;border-bottom:0px solid var(--global-palette6, #718096);}.wp-block-kadence-advancedheading.kt-adv-heading4674_84dc8e-f7 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4674_84dc8e-f7[data-kb-block=\"kb-adv-heading4674_84dc8e-f7\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4674_84dc8e-f7 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4674_84dc8e-f7[data-kb-block=\"kb-adv-heading4674_84dc8e-f7\"] img.kb-inline-image{width:150px;vertical-align:baseline;}.wp-block-kadence-advancedheading.kt-adv-heading4674_84dc8e-f7[data-kb-block=\"kb-adv-heading4674_84dc8e-f7\"] a, .kt-adv-heading-link4674_84dc8e-f7, .kt-adv-heading-link4674_84dc8e-f7 .kt-adv-heading4674_84dc8e-f7[data-kb-block=\"kb-adv-heading4674_84dc8e-f7\"]{color:var(--global-palette3, #1A202C);}.wp-block-kadence-advancedheading.kt-adv-heading4674_84dc8e-f7[data-kb-block=\"kb-adv-heading4674_84dc8e-f7\"] a:hover, .kt-adv-heading-link4674_84dc8e-f7:hover, .kt-adv-heading-link4674_84dc8e-f7:hover .kt-adv-heading4674_84dc8e-f7[data-kb-block=\"kb-adv-heading4674_84dc8e-f7\"]{color:var(--global-palette3, #1A202C);}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading4674_84dc8e-f7, .wp-block-kadence-advancedheading.kt-adv-heading4674_84dc8e-f7[data-kb-block=\"kb-adv-heading4674_84dc8e-f7\"]{border-bottom:0px solid var(--global-palette6, #718096);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4674_84dc8e-f7, .wp-block-kadence-advancedheading.kt-adv-heading4674_84dc8e-f7[data-kb-block=\"kb-adv-heading4674_84dc8e-f7\"]{border-bottom:0px solid var(--global-palette6, #718096);}}<\/style>\n<p class=\"kt-adv-heading4674_84dc8e-f7 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4674_84dc8e-f7\">\u0641\u064a\u0647\u0627 \u062a\u0633\u064a\u0637\u0631 \u0623\u0641\u0643\u0627\u0631 \u0645\u0639\u064a\u0646\u0629 \u0639\u0644\u0649 \u0639\u0642\u0644 \u0627\u0644\u0645\u0631\u064a\u0636 \u0627\u0644\u0646\u0641\u0633\u064a \u0628\u0634\u0643\u0644 \u0642\u0647\u0631\u064a \u0648 \u062a\u062c\u0639\u0644\u0647 \u064a\u0643\u0631\u0631 \u0623\u0641\u0639\u0627\u0644 \u0628\u0635\u0648\u0631\u0629 \u0645\u0628\u0627\u0644\u063a \u0641\u064a\u0647\u0627 \u0648\u062a\u062e\u062a\u0644\u0641 \u0646\u0648\u0639\u064a\u0629 \u0647\u0630\u0647 \u0627\u0644\u0623\u0641\u0643\u0627\u0631 \u0648\u0634\u062f\u062a\u0647\u0627 \u0645\u0646 \u0634\u062e\u0635 \u0625\u0644\u0649 \u0622\u062e\u0631\u060c \u0641\u0623\u062d\u064a\u0627\u0646\u0627 \u062a\u0643\u0648\u0646 \u0647\u0630\u0647 \u0627\u0644\u0623\u0641\u0643\u0627\u0631 \u0645\u062a\u0639\u0644\u0642\u0629 \u0628\u0634\u062e\u0635 \u0645\u0627 \u0641\u064a \u062d\u064a\u0627\u0629 \u0627\u0644\u0641\u0631\u062f\u060c \u0623\u0648 \u062a\u0643\u0648\u0646 \u0628\u0634\u0623\u0646 \u0645\u0639\u062a\u0642\u062f\u0627\u062a\u0647 \u0627\u0644\u062f\u064a\u0646\u064a\u0629 \u0623\u0648 \u0627\u0644\u0641\u0643\u0631\u064a\u0629 \u0645\u062b\u0644\u0627\u064b\u060c\u00a0 \u0648\u0642\u062f \u062a\u0643\u0648\u0646 \u0628\u0634\u0623\u0646 \u0639\u0627\u062f\u0627\u062a\u0647 \u0645\u062b\u0644 \u0646\u0648\u0639 \u0627\u0644\u0648\u0633\u0648\u0627\u0633 \u0627\u0644\u0645\u062a\u0639\u0644\u0642 \u0628\u0627\u0644\u0646\u0638\u0627\u0641\u0629 \u0627\u0644\u0634\u062e\u0635\u064a\u0629\u060c \u0648\u0647\u0630\u0627 \u0627\u0644\u0646\u0648\u0639 \u0623\u064a\u0636\u0627\u064b \u0645\u0646 \u0623\u0634\u0647\u0631 \u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629 \u0648\u0639\u0644\u0627\u062c\u0647\u0627 \u064a\u062d\u062a\u0627\u062c \u0627\u0644\u0649 \u0635\u0628\u0631 \u0648\u0648\u0642\u062a \u0637\u0648\u064a\u0644.<\/p>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-6 kt-pane4674_8c501b-d0\"><h4 class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0645\u0627 \u0628\u0639\u062f \u0627\u0644\u0635\u062f\u0645\u0629<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/h4><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.kadence-column4674_527575-d8 > .kt-inside-inner-col,.kadence-column4674_527575-d8 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4674_527575-d8 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4674_527575-d8 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4674_527575-d8 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4674_527575-d8 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4674_527575-d8{position:relative;}@media all and (max-width: 1024px){.kadence-column4674_527575-d8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4674_527575-d8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4674_527575-d8\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4674_eab3c2-7a, .wp-block-kadence-advancedheading.kt-adv-heading4674_eab3c2-7a[data-kb-block=\"kb-adv-heading4674_eab3c2-7a\"]{margin-bottom:0px;font-style:normal;border-bottom:0px solid var(--global-palette6, #718096);}.wp-block-kadence-advancedheading.kt-adv-heading4674_eab3c2-7a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4674_eab3c2-7a[data-kb-block=\"kb-adv-heading4674_eab3c2-7a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4674_eab3c2-7a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4674_eab3c2-7a[data-kb-block=\"kb-adv-heading4674_eab3c2-7a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}.wp-block-kadence-advancedheading.kt-adv-heading4674_eab3c2-7a[data-kb-block=\"kb-adv-heading4674_eab3c2-7a\"] a, .kt-adv-heading-link4674_eab3c2-7a, .kt-adv-heading-link4674_eab3c2-7a .kt-adv-heading4674_eab3c2-7a[data-kb-block=\"kb-adv-heading4674_eab3c2-7a\"]{color:var(--global-palette3, #1A202C);}.wp-block-kadence-advancedheading.kt-adv-heading4674_eab3c2-7a[data-kb-block=\"kb-adv-heading4674_eab3c2-7a\"] a:hover, .kt-adv-heading-link4674_eab3c2-7a:hover, .kt-adv-heading-link4674_eab3c2-7a:hover .kt-adv-heading4674_eab3c2-7a[data-kb-block=\"kb-adv-heading4674_eab3c2-7a\"]{color:var(--global-palette3, #1A202C);}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading4674_eab3c2-7a, .wp-block-kadence-advancedheading.kt-adv-heading4674_eab3c2-7a[data-kb-block=\"kb-adv-heading4674_eab3c2-7a\"]{border-bottom:0px solid var(--global-palette6, #718096);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4674_eab3c2-7a, .wp-block-kadence-advancedheading.kt-adv-heading4674_eab3c2-7a[data-kb-block=\"kb-adv-heading4674_eab3c2-7a\"]{border-bottom:0px solid var(--global-palette6, #718096);}}<\/style>\n<p class=\"kt-adv-heading4674_eab3c2-7a wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4674_eab3c2-7a\">\u0641\u064a \u0647\u0630\u0627 \u0627\u0644\u0646\u0648\u0639 \u0645\u0646 \u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629\u00a0 \u064a\u0639\u0627\u0646\u064a \u0627\u0644\u0645\u0631\u064a\u0636 \u0645\u0646 \u0635\u0639\u0648\u0628\u0629 \u0641\u064a \u0627\u0644\u062a\u0643\u064a\u0641 \u0645\u0639 \u0645\u062c\u0631\u064a\u0627\u062a \u062d\u064a\u0627\u062a\u0647 \u0628\u0639\u062f \u0627\u0644\u062a\u0639\u0631\u0636 \u0644\u0636\u063a\u0648\u0637\u0627\u062a \u0634\u062f\u064a\u062f\u0629 \u0623\u0648 \u062d\u0627\u062f\u062b\u0629 \u0623\u062f\u062a\u00a0 \u0644\u0635\u062f\u0645\u0629 \u062f\u0645\u0627\u063a\u064a\u0629 \u0639\u0646\u064a\u0641\u0629.<\/p>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-7 kt-pane4674_60baa5-5f\"><h4 class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0645\u0631\u062a\u0628\u0637\u0629 \u0628\u0627\u0644\u0623\u0639\u0631\u0627\u0636 \u0627\u0644\u062c\u0633\u062f\u064a\u0629<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/h4><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.kadence-column4674_fdc8c4-5d > .kt-inside-inner-col,.kadence-column4674_fdc8c4-5d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4674_fdc8c4-5d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4674_fdc8c4-5d > .kt-inside-inner-col{flex-direction:column;}.kadence-column4674_fdc8c4-5d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4674_fdc8c4-5d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4674_fdc8c4-5d{position:relative;}@media all and (max-width: 1024px){.kadence-column4674_fdc8c4-5d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4674_fdc8c4-5d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4674_fdc8c4-5d\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4674_3dff90-19, .wp-block-kadence-advancedheading.kt-adv-heading4674_3dff90-19[data-kb-block=\"kb-adv-heading4674_3dff90-19\"]{margin-bottom:0px;font-style:normal;border-bottom:0px solid var(--global-palette6, #718096);}.wp-block-kadence-advancedheading.kt-adv-heading4674_3dff90-19 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4674_3dff90-19[data-kb-block=\"kb-adv-heading4674_3dff90-19\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4674_3dff90-19 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4674_3dff90-19[data-kb-block=\"kb-adv-heading4674_3dff90-19\"] img.kb-inline-image{width:150px;vertical-align:baseline;}.wp-block-kadence-advancedheading.kt-adv-heading4674_3dff90-19[data-kb-block=\"kb-adv-heading4674_3dff90-19\"] a, .kt-adv-heading-link4674_3dff90-19, .kt-adv-heading-link4674_3dff90-19 .kt-adv-heading4674_3dff90-19[data-kb-block=\"kb-adv-heading4674_3dff90-19\"]{color:var(--global-palette3, #1A202C);}.wp-block-kadence-advancedheading.kt-adv-heading4674_3dff90-19[data-kb-block=\"kb-adv-heading4674_3dff90-19\"] a:hover, .kt-adv-heading-link4674_3dff90-19:hover, .kt-adv-heading-link4674_3dff90-19:hover .kt-adv-heading4674_3dff90-19[data-kb-block=\"kb-adv-heading4674_3dff90-19\"]{color:var(--global-palette3, #1A202C);}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading4674_3dff90-19, .wp-block-kadence-advancedheading.kt-adv-heading4674_3dff90-19[data-kb-block=\"kb-adv-heading4674_3dff90-19\"]{border-bottom:0px solid var(--global-palette6, #718096);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4674_3dff90-19, .wp-block-kadence-advancedheading.kt-adv-heading4674_3dff90-19[data-kb-block=\"kb-adv-heading4674_3dff90-19\"]{border-bottom:0px solid var(--global-palette6, #718096);}}<\/style>\n<p class=\"kt-adv-heading4674_3dff90-19 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4674_3dff90-19\">\u062a\u0646\u0634\u0623 \u0628\u0639\u0636 \u0627\u0644\u0623\u0645\u0631\u0627\u0636 \u0627\u0644\u0646\u0641\u0633\u064a\u0629 \u0646\u062a\u064a\u062c\u0629 \u0627\u0644\u0625\u0635\u0627\u0628\u0629 \u0628\u0627\u0644\u0623\u0645\u0631\u0627\u0636 \u0627\u0644\u062c\u0633\u062f\u064a\u0629 \u0630\u0627\u062a \u0627\u0644\u0623\u0639\u0631\u0627\u0636 \u0627\u0644\u0642\u0648\u064a\u0629 \u0648\u0627\u0644\u0645\u0632\u0639\u062c\u0629\u060c \u0641\u0639\u0644\u0649 \u0633\u0628\u064a\u0644 \u0627\u0644\u0645\u062b\u0627\u0644 \u064a\u0634\u0639\u0631 \u0627\u0644\u0634\u062e\u0635 \u0627\u0644\u0645\u0635\u0627\u0628 \u0628\u0627\u0644\u064a\u0623\u0633 \u0648\u0639\u062f\u0645 \u0627\u0644\u0631\u063a\u0628\u0629 \u0641\u064a \u0627\u0644\u062d\u064a\u0627\u0629 \u0628\u0639\u062f \u0625\u0635\u0627\u0628\u062a\u0647 \u0628\u0641\u0642\u062f\u0627\u0646 \u0627\u0644\u0628\u0635\u0631 \u0623\u0648 \u0641\u0642\u062f \u0623\u062d\u062f \u0623\u0639\u0636\u0627\u0626\u0647.<\/p>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-8 kt-pane4674_a92a81-da\"><h4 class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0623\u0643\u0644<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/h4><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.kadence-column4674_82f805-93 > .kt-inside-inner-col,.kadence-column4674_82f805-93 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4674_82f805-93 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4674_82f805-93 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4674_82f805-93 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4674_82f805-93 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4674_82f805-93{position:relative;}@media all and (max-width: 1024px){.kadence-column4674_82f805-93 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4674_82f805-93 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4674_82f805-93\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4674_7ae9aa-c3, .wp-block-kadence-advancedheading.kt-adv-heading4674_7ae9aa-c3[data-kb-block=\"kb-adv-heading4674_7ae9aa-c3\"]{margin-bottom:0px;font-style:normal;border-bottom:0px solid var(--global-palette6, #718096);}.wp-block-kadence-advancedheading.kt-adv-heading4674_7ae9aa-c3 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4674_7ae9aa-c3[data-kb-block=\"kb-adv-heading4674_7ae9aa-c3\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4674_7ae9aa-c3 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4674_7ae9aa-c3[data-kb-block=\"kb-adv-heading4674_7ae9aa-c3\"] img.kb-inline-image{width:150px;vertical-align:baseline;}.wp-block-kadence-advancedheading.kt-adv-heading4674_7ae9aa-c3[data-kb-block=\"kb-adv-heading4674_7ae9aa-c3\"] a, .kt-adv-heading-link4674_7ae9aa-c3, .kt-adv-heading-link4674_7ae9aa-c3 .kt-adv-heading4674_7ae9aa-c3[data-kb-block=\"kb-adv-heading4674_7ae9aa-c3\"]{color:var(--global-palette3, #1A202C);}.wp-block-kadence-advancedheading.kt-adv-heading4674_7ae9aa-c3[data-kb-block=\"kb-adv-heading4674_7ae9aa-c3\"] a:hover, .kt-adv-heading-link4674_7ae9aa-c3:hover, .kt-adv-heading-link4674_7ae9aa-c3:hover .kt-adv-heading4674_7ae9aa-c3[data-kb-block=\"kb-adv-heading4674_7ae9aa-c3\"]{color:var(--global-palette3, #1A202C);}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading4674_7ae9aa-c3, .wp-block-kadence-advancedheading.kt-adv-heading4674_7ae9aa-c3[data-kb-block=\"kb-adv-heading4674_7ae9aa-c3\"]{border-bottom:0px solid var(--global-palette6, #718096);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4674_7ae9aa-c3, .wp-block-kadence-advancedheading.kt-adv-heading4674_7ae9aa-c3[data-kb-block=\"kb-adv-heading4674_7ae9aa-c3\"]{border-bottom:0px solid var(--global-palette6, #718096);}}<\/style>\n<p class=\"kt-adv-heading4674_7ae9aa-c3 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4674_7ae9aa-c3\">\u0648\u0647\u064a \u0646\u0648\u0639 \u0645\u0646 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0645\u0631\u062a\u0628\u0637\u0629 \u0628\u0627\u0644\u063a\u0630\u0627\u0621 \u0648 \u062a\u0646\u0627\u0648\u0644 \u0627\u0644\u0637\u0639\u0627\u0645\u060c \u0645\u062b\u0644 \u0641\u0642\u062f\u0627\u0646 \u0627\u0644\u0634\u0647\u064a\u0629 \u0627\u0644\u0639\u0635\u0628\u064a \u0627\u0644\u0630\u064a \u064a\u0645\u062a\u0646\u0639 \u0641\u064a\u0647 \u0627\u0644\u0645\u0631\u064a\u0636 \u0639\u0646 \u062a\u0646\u0627\u0648\u0644 \u0627\u0644\u0637\u0639\u0627\u0645 \u0628\u0633\u0628\u0628 \u0636\u063a\u0648\u0637 \u0646\u0641\u0633\u064a\u0629 \u0623\u0648 \u0627\u0644\u062d\u0627\u0644\u0629 \u0627\u0644\u0645\u0639\u0627\u0643\u0633\u0629 \u0648\u0647\u064a \u0627\u0644\u0634\u0631\u0627\u0647\u0629 \u0627\u0644\u0639\u0635\u0628\u064a\u0629 \u0627\u0644\u0630\u064a \u064a\u062a\u0644\u0630\u0630 \u0641\u064a\u0647 \u0627\u0644\u0634\u062e\u0635 \u0628\u0639\u0645\u0644\u064a\u0629 \u062a\u0646\u0627\u0648\u0644 \u0627\u0644\u063a\u0630\u0627\u0621\u060c \u0648\u064a\u0639\u0645\u062f \u0625\u0644\u0649 \u0627\u0644\u0627\u0633\u062a\u0641\u0631\u0627\u063a \u0627\u0644\u0645\u062a\u0639\u0645\u062f \u0628\u0639\u062f \u062a\u0646\u0627\u0648\u0644 \u0627\u0644\u0637\u0639\u0627\u0645 \u0644\u064a\u0633\u062a\u0637\u064a\u0639 \u062a\u0646\u0627\u0648\u0644 \u0648\u062c\u0628\u0629 \u062c\u062f\u064a\u062f\u0629 \u0648\u0647\u0643\u0630\u0627.<\/p>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-9 kt-pane4674_7c8c57-9f\"><h4 class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0634\u062e\u0635\u064a\u0629<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/h4><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\"><style>.kadence-column4674_85fdfb-c9 > .kt-inside-inner-col,.kadence-column4674_85fdfb-c9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4674_85fdfb-c9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4674_85fdfb-c9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4674_85fdfb-c9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4674_85fdfb-c9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4674_85fdfb-c9{position:relative;}@media all and (max-width: 1024px){.kadence-column4674_85fdfb-c9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4674_85fdfb-c9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4674_85fdfb-c9\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4674_e7c6da-a0, .wp-block-kadence-advancedheading.kt-adv-heading4674_e7c6da-a0[data-kb-block=\"kb-adv-heading4674_e7c6da-a0\"]{margin-bottom:0px;font-style:normal;border-bottom:0px solid var(--global-palette6, #718096);}.wp-block-kadence-advancedheading.kt-adv-heading4674_e7c6da-a0 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4674_e7c6da-a0[data-kb-block=\"kb-adv-heading4674_e7c6da-a0\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4674_e7c6da-a0 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4674_e7c6da-a0[data-kb-block=\"kb-adv-heading4674_e7c6da-a0\"] img.kb-inline-image{width:150px;vertical-align:baseline;}.wp-block-kadence-advancedheading.kt-adv-heading4674_e7c6da-a0[data-kb-block=\"kb-adv-heading4674_e7c6da-a0\"] a, .kt-adv-heading-link4674_e7c6da-a0, .kt-adv-heading-link4674_e7c6da-a0 .kt-adv-heading4674_e7c6da-a0[data-kb-block=\"kb-adv-heading4674_e7c6da-a0\"]{color:var(--global-palette3, #1A202C);}.wp-block-kadence-advancedheading.kt-adv-heading4674_e7c6da-a0[data-kb-block=\"kb-adv-heading4674_e7c6da-a0\"] a:hover, .kt-adv-heading-link4674_e7c6da-a0:hover, .kt-adv-heading-link4674_e7c6da-a0:hover .kt-adv-heading4674_e7c6da-a0[data-kb-block=\"kb-adv-heading4674_e7c6da-a0\"]{color:var(--global-palette3, #1A202C);}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading4674_e7c6da-a0, .wp-block-kadence-advancedheading.kt-adv-heading4674_e7c6da-a0[data-kb-block=\"kb-adv-heading4674_e7c6da-a0\"]{border-bottom:0px solid var(--global-palette6, #718096);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4674_e7c6da-a0, .wp-block-kadence-advancedheading.kt-adv-heading4674_e7c6da-a0[data-kb-block=\"kb-adv-heading4674_e7c6da-a0\"]{border-bottom:0px solid var(--global-palette6, #718096);}}<\/style>\n<p class=\"kt-adv-heading4674_e7c6da-a0 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4674_e7c6da-a0\">\u062a\u062a\u0646\u0648\u0639 \u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0634\u062e\u0635\u064a\u0629 \u0648\u062a\u062a\u0641\u0631\u0639 \u0625\u0644\u0649 \u0623\u0643\u062b\u0631 \u0645\u0646 \u0646\u0648\u0639 \u0625\u0644\u0627 \u0623\u0646\u0647\u0627 \u062a\u062a\u0641\u0642 \u0641\u064a \u0633\u0644\u0648\u0643 \u0627\u0644\u0645\u0631\u064a\u0636 \u0645\u0633\u0644\u0643 \u0627\u062c\u062a\u0645\u0627\u0639\u064a \u063a\u064a\u0631 \u0637\u0628\u064a\u0639\u064a\u060c \u0648\u0643\u0645\u062b\u0627\u0644 \u0639\u0644\u0649 \u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0634\u062e\u0635\u064a\u0629: \u0627\u0644\u0627\u0646\u0637\u0648\u0627\u0626\u064a\u0629 \u0648\u0627\u0644\u0646\u0631\u062c\u0633\u064a\u0629 \u0648 \u062c\u0646\u0648\u0646 \u0627\u0644\u0639\u0638\u0645\u0629 \u0648\u0639\u0642\u062f\u0629 \u0627\u0644\u0627\u0636\u0637\u0647\u0627\u062f\u060c \u0648\u063a\u064a\u0631 \u0630\u0644\u0643 \u0645\u0646 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u062a\u064a \u062a\u062c\u0639\u0644 \u0627\u0644\u0645\u0631\u064a\u0636 \u064a\u062a\u0635\u0631\u0641 \u0628\u0634\u0643\u0644 \u063a\u064a\u0631 \u0637\u0628\u064a\u0639\u064a \u0627\u062c\u062a\u0645\u0627\u0639\u064a\u0627\u064b \u0641\u064a \u0627\u0644\u062f\u0648\u0627\u0626\u0631 \u0627\u0644\u0645\u062d\u064a\u0637\u0629 \u0628\u0647.<\/p>\n<\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column4674_6945bc-5a > .kt-inside-inner-col,.kadence-column4674_6945bc-5a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4674_6945bc-5a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4674_6945bc-5a > .kt-inside-inner-col{flex-direction:column;}.kadence-column4674_6945bc-5a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4674_6945bc-5a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4674_6945bc-5a{position:relative;}.kadence-column4674_6945bc-5a, .kt-inside-inner-col > .kadence-column4674_6945bc-5a:not(.specificity){margin-bottom:80px;}@media all and (max-width: 1024px){.kadence-column4674_6945bc-5a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column4674_6945bc-5a, .kt-inside-inner-col > .kadence-column4674_6945bc-5a:not(.specificity){margin-bottom:60px;}}@media all and (max-width: 767px){.kadence-column4674_6945bc-5a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4674_6945bc-5a single_article_single_content_section\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4674_8f678d-7b, .wp-block-kadence-advancedheading.kt-adv-heading4674_8f678d-7b[data-kb-block=\"kb-adv-heading4674_8f678d-7b\"]{margin-bottom:32px;font-size:32px;line-height:41px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4674_8f678d-7b mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4674_8f678d-7b[data-kb-block=\"kb-adv-heading4674_8f678d-7b\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4674_8f678d-7b img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4674_8f678d-7b[data-kb-block=\"kb-adv-heading4674_8f678d-7b\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4674_8f678d-7b, .wp-block-kadence-advancedheading.kt-adv-heading4674_8f678d-7b[data-kb-block=\"kb-adv-heading4674_8f678d-7b\"]{margin-bottom:24px;font-size:24px;line-height:29px;}}<\/style>\n<h2 class=\"kt-adv-heading4674_8f678d-7b heading_h3 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4674_8f678d-7b\">\u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628 \u0627\u0644\u0646\u0641\u0633\u064a \u0623\u0639\u0631\u0627\u0636\u0647<\/h2>\n\n\n<style>.kadence-column4674_b22906-75 > .kt-inside-inner-col,.kadence-column4674_b22906-75 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4674_b22906-75 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4674_b22906-75 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4674_b22906-75 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4674_b22906-75 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4674_b22906-75{position:relative;}@media all and (max-width: 1024px){.kadence-column4674_b22906-75 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4674_b22906-75 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4674_b22906-75\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4674_5866d6-2a, .wp-block-kadence-advancedheading.kt-adv-heading4674_5866d6-2a[data-kb-block=\"kb-adv-heading4674_5866d6-2a\"]{margin-bottom:25px;font-style:normal;border-bottom:0px solid var(--global-palette6, #718096);}.wp-block-kadence-advancedheading.kt-adv-heading4674_5866d6-2a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4674_5866d6-2a[data-kb-block=\"kb-adv-heading4674_5866d6-2a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4674_5866d6-2a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4674_5866d6-2a[data-kb-block=\"kb-adv-heading4674_5866d6-2a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}.wp-block-kadence-advancedheading.kt-adv-heading4674_5866d6-2a[data-kb-block=\"kb-adv-heading4674_5866d6-2a\"] a, .kt-adv-heading-link4674_5866d6-2a, .kt-adv-heading-link4674_5866d6-2a .kt-adv-heading4674_5866d6-2a[data-kb-block=\"kb-adv-heading4674_5866d6-2a\"]{color:var(--global-palette3, #1A202C);}.wp-block-kadence-advancedheading.kt-adv-heading4674_5866d6-2a[data-kb-block=\"kb-adv-heading4674_5866d6-2a\"] a:hover, .kt-adv-heading-link4674_5866d6-2a:hover, .kt-adv-heading-link4674_5866d6-2a:hover .kt-adv-heading4674_5866d6-2a[data-kb-block=\"kb-adv-heading4674_5866d6-2a\"]{color:var(--global-palette3, #1A202C);}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading4674_5866d6-2a, .wp-block-kadence-advancedheading.kt-adv-heading4674_5866d6-2a[data-kb-block=\"kb-adv-heading4674_5866d6-2a\"]{border-bottom:0px solid var(--global-palette6, #718096);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4674_5866d6-2a, .wp-block-kadence-advancedheading.kt-adv-heading4674_5866d6-2a[data-kb-block=\"kb-adv-heading4674_5866d6-2a\"]{border-bottom:0px solid var(--global-palette6, #718096);}}<\/style>\n<p class=\"kt-adv-heading4674_5866d6-2a wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4674_5866d6-2a\">\u064a\u062e\u062a\u0644\u0641 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628 \u0627\u0644\u0646\u0641\u0633\u064a \u0623\u0639\u0631\u0627\u0636\u0647 \u0648\u0637\u0631\u064a\u0642\u0629 \u0639\u0644\u0627\u062c\u0647 \u062a\u0628\u0639\u0627\u064b \u0644\u0646\u0648\u0639\u0647 \u0648\u0634\u062f\u062a\u0647\u060c \u0648\u0645\u0639 \u0630\u0644\u0643 \u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0639\u0631\u0627\u0636 \u0627\u0644\u0645\u0634\u062a\u0631\u0643\u0629 \u0623\u0648 \u0627\u0644\u062a\u064a \u064a\u0645\u0643\u0646 \u0623\u0646 \u062a\u062a\u0634\u0627\u0628\u0647 \u0628\u064a\u0646 \u0623\u063a\u0644\u0628 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading4674_10bf1c-8c, .wp-block-kadence-advancedheading.kt-adv-heading4674_10bf1c-8c[data-kb-block=\"kb-adv-heading4674_10bf1c-8c\"]{margin-bottom:25px;font-style:normal;border-bottom:0px solid var(--global-palette6, #718096);}.wp-block-kadence-advancedheading.kt-adv-heading4674_10bf1c-8c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4674_10bf1c-8c[data-kb-block=\"kb-adv-heading4674_10bf1c-8c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4674_10bf1c-8c img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4674_10bf1c-8c[data-kb-block=\"kb-adv-heading4674_10bf1c-8c\"] img.kb-inline-image{width:150px;vertical-align:baseline;}.wp-block-kadence-advancedheading.kt-adv-heading4674_10bf1c-8c[data-kb-block=\"kb-adv-heading4674_10bf1c-8c\"] a, .kt-adv-heading-link4674_10bf1c-8c, .kt-adv-heading-link4674_10bf1c-8c .kt-adv-heading4674_10bf1c-8c[data-kb-block=\"kb-adv-heading4674_10bf1c-8c\"]{color:var(--global-palette3, #1A202C);}.wp-block-kadence-advancedheading.kt-adv-heading4674_10bf1c-8c[data-kb-block=\"kb-adv-heading4674_10bf1c-8c\"] a:hover, .kt-adv-heading-link4674_10bf1c-8c:hover, .kt-adv-heading-link4674_10bf1c-8c:hover .kt-adv-heading4674_10bf1c-8c[data-kb-block=\"kb-adv-heading4674_10bf1c-8c\"]{color:var(--global-palette3, #1A202C);}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading4674_10bf1c-8c, .wp-block-kadence-advancedheading.kt-adv-heading4674_10bf1c-8c[data-kb-block=\"kb-adv-heading4674_10bf1c-8c\"]{border-bottom:0px solid var(--global-palette6, #718096);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4674_10bf1c-8c, .wp-block-kadence-advancedheading.kt-adv-heading4674_10bf1c-8c[data-kb-block=\"kb-adv-heading4674_10bf1c-8c\"]{border-bottom:0px solid var(--global-palette6, #718096);}}<\/style>\n<p class=\"kt-adv-heading4674_10bf1c-8c wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4674_10bf1c-8c\">\u0623\u062d\u062f \u0623\u0628\u0631\u0632 \u0647\u0630\u0647 \u0627\u0644\u0623\u0639\u0631\u0627\u0636 \u0647\u0648 \u0627\u0644\u062a\u063a\u064a\u0631 \u0641\u064a \u0627\u0644\u0645\u0632\u0627\u062c\u060c \u062d\u064a\u062b \u0642\u062f \u064a\u0634\u0639\u0631 \u0627\u0644\u0634\u062e\u0635 \u0628\u0627\u0644\u0627\u0643\u062a\u0626\u0627\u0628 \u0623\u0648\u00a0<a href=\"\/ar\/%d8%b9%d9%88%d8%a7%d9%85%d9%84-%d8%aa%d8%b2%d9%8a%d8%af-%d9%85%d9%86-%d8%b4%d8%b9%d9%88%d8%b1%d9%83-%d8%a8%d8%a7%d9%84%d9%82%d9%84%d9%82-%d9%88%d8%a7%d9%84%d8%aa%d9%88%d8%aa%d8%b1\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u0627\u0644\u0642\u0644\u0642 \u0628\u0634\u0643\u0644 \u0645\u062a\u0643\u0631\u0631<\/a>. \u0642\u062f \u062a\u062a\u0631\u0627\u0641\u0642 \u0647\u0630\u0647 \u0627\u0644\u0645\u0634\u0627\u0639\u0631 \u0645\u0639 \u0627\u0644\u0634\u0639\u0648\u0631 \u0628\u0627\u0644\u0639\u0632\u0644\u0629 \u0648\u0641\u0642\u062f\u0627\u0646 \u0627\u0644\u0627\u0647\u062a\u0645\u0627\u0645 \u0628\u0627\u0644\u0623\u0646\u0634\u0637\u0629 \u0627\u0644\u062a\u064a \u0643\u0627\u0646\u062a \u0645\u0645\u062a\u0639\u0629 \u0641\u064a \u0627\u0644\u0633\u0627\u0628\u0642. \u0645\u0646 \u0627\u0644\u0623\u0639\u0631\u0627\u0636 \u0627\u0644\u0623\u062e\u0631\u0649 \u0627\u0644\u062a\u064a \u0642\u062f \u062a\u0638\u0647\u0631 \u0647\u064a \u0627\u0644\u062a\u063a\u064a\u0631\u0627\u062a \u0641\u064a \u0627\u0644\u0646\u0648\u0645\u060c \u0645\u062b\u0644 \u0627\u0644\u0623\u0631\u0642 \u0623\u0648 \u0627\u0644\u0646\u0648\u0645 \u0627\u0644\u0645\u0641\u0631\u0637\u060c \u0648\u0647\u0648 \u0645\u0627 \u064a\u0645\u0643\u0646 \u0623\u0646 \u064a\u0624\u062b\u0631 \u0639\u0644\u0649 \u0645\u0633\u062a\u0648\u0649 \u0627\u0644\u0637\u0627\u0642\u0629 \u0648\u0627\u0644\u062a\u0631\u0643\u064a\u0632 \u062e\u0644\u0627\u0644 \u0627\u0644\u064a\u0648\u0645.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading4674_dd77f3-2c, .wp-block-kadence-advancedheading.kt-adv-heading4674_dd77f3-2c[data-kb-block=\"kb-adv-heading4674_dd77f3-2c\"]{margin-bottom:0px;font-style:normal;border-bottom:0px solid var(--global-palette6, #718096);}.wp-block-kadence-advancedheading.kt-adv-heading4674_dd77f3-2c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4674_dd77f3-2c[data-kb-block=\"kb-adv-heading4674_dd77f3-2c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4674_dd77f3-2c img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4674_dd77f3-2c[data-kb-block=\"kb-adv-heading4674_dd77f3-2c\"] img.kb-inline-image{width:150px;vertical-align:baseline;}.wp-block-kadence-advancedheading.kt-adv-heading4674_dd77f3-2c[data-kb-block=\"kb-adv-heading4674_dd77f3-2c\"] a, .kt-adv-heading-link4674_dd77f3-2c, .kt-adv-heading-link4674_dd77f3-2c .kt-adv-heading4674_dd77f3-2c[data-kb-block=\"kb-adv-heading4674_dd77f3-2c\"]{color:var(--global-palette3, #1A202C);}.wp-block-kadence-advancedheading.kt-adv-heading4674_dd77f3-2c[data-kb-block=\"kb-adv-heading4674_dd77f3-2c\"] a:hover, .kt-adv-heading-link4674_dd77f3-2c:hover, .kt-adv-heading-link4674_dd77f3-2c:hover .kt-adv-heading4674_dd77f3-2c[data-kb-block=\"kb-adv-heading4674_dd77f3-2c\"]{color:var(--global-palette3, #1A202C);}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading4674_dd77f3-2c, .wp-block-kadence-advancedheading.kt-adv-heading4674_dd77f3-2c[data-kb-block=\"kb-adv-heading4674_dd77f3-2c\"]{border-bottom:0px solid var(--global-palette6, #718096);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4674_dd77f3-2c, .wp-block-kadence-advancedheading.kt-adv-heading4674_dd77f3-2c[data-kb-block=\"kb-adv-heading4674_dd77f3-2c\"]{border-bottom:0px solid var(--global-palette6, #718096);}}<\/style>\n<p class=\"kt-adv-heading4674_dd77f3-2c wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4674_dd77f3-2c\">\u0643\u0645\u0627 \u064a\u0645\u0643\u0646 \u0623\u0646 \u062a\u0634\u0645\u0644 \u0627\u0644\u0623\u0639\u0631\u0627\u0636\u00a0<a href=\"\/ar\/%d8%a3%d8%b3%d8%a8%d8%a7%d8%a8-%d9%88%d8%b9%d9%84%d8%a7%d8%ac-%d8%a7%d8%b6%d8%b7%d8%b1%d8%a7%d8%a8-%d8%a7%d9%84%d8%b4%d8%b1%d8%a7%d9%87%d8%a9-%d8%b9%d9%86%d8%af-%d8%aa%d9%86%d8%a7%d9%88%d9%84-%d8%a7\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u0627\u0644\u062a\u063a\u064a\u0631\u0627\u062a \u0641\u064a \u0627\u0644\u0634\u0647\u064a\u0629<\/a>\u060c \u0645\u0645\u0627 \u064a\u0624\u062f\u064a \u0625\u0644\u0649 \u0641\u0642\u062f\u0627\u0646 \u0627\u0644\u0648\u0632\u0646 \u0623\u0648 \u0627\u0643\u062a\u0633\u0627\u0628\u0647 \u0628\u0634\u0643\u0644 \u063a\u064a\u0631 \u0645\u062a\u0648\u0642\u0639\u060c \u0628\u0627\u0644\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0645\u0634\u0643\u0644\u0627\u062a \u0627\u0644\u062a\u0631\u0643\u064a\u0632 \u0648\u0635\u0639\u0648\u0628\u0629 \u0627\u062a\u062e\u0627\u0630 \u0627\u0644\u0642\u0631\u0627\u0631\u0627\u062a \u062a\u0639\u062a\u0628\u0631 \u0623\u064a\u0636\u064b\u0627 \u0645\u0646 \u0627\u0644\u0623\u0639\u0631\u0627\u0636 \u0627\u0644\u0634\u0627\u0626\u0639\u0629\u060c \u062d\u064a\u062b \u064a\u062c\u062f \u0627\u0644\u0634\u062e\u0635 \u0635\u0639\u0648\u0628\u0629 \u0641\u064a \u0627\u0644\u062a\u0631\u0643\u064a\u0632 \u0623\u0648 \u062a\u0630\u0643\u0631 \u0627\u0644\u0623\u0645\u0648\u0631 \u0627\u0644\u064a\u0648\u0645\u064a\u0629.<\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column4674_78906c-90 > .kt-inside-inner-col,.kadence-column4674_78906c-90 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4674_78906c-90 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4674_78906c-90 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4674_78906c-90 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4674_78906c-90 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4674_78906c-90{position:relative;}.kadence-column4674_78906c-90, .kt-inside-inner-col > .kadence-column4674_78906c-90:not(.specificity){margin-bottom:80px;}@media all and (max-width: 1024px){.kadence-column4674_78906c-90 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column4674_78906c-90, .kt-inside-inner-col > .kadence-column4674_78906c-90:not(.specificity){margin-bottom:60px;}}@media all and (max-width: 767px){.kadence-column4674_78906c-90 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4674_78906c-90 single_article_single_content_section\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4674_ceb0ab-12, .wp-block-kadence-advancedheading.kt-adv-heading4674_ceb0ab-12[data-kb-block=\"kb-adv-heading4674_ceb0ab-12\"]{margin-bottom:24px;font-size:32px;line-height:41px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4674_ceb0ab-12 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4674_ceb0ab-12[data-kb-block=\"kb-adv-heading4674_ceb0ab-12\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4674_ceb0ab-12 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4674_ceb0ab-12[data-kb-block=\"kb-adv-heading4674_ceb0ab-12\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4674_ceb0ab-12, .wp-block-kadence-advancedheading.kt-adv-heading4674_ceb0ab-12[data-kb-block=\"kb-adv-heading4674_ceb0ab-12\"]{font-size:24px;line-height:29px;}}<\/style>\n<h2 class=\"kt-adv-heading4674_ceb0ab-12 heading_h3 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4674_ceb0ab-12\">\u062a\u0634\u062e\u064a\u0635 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628 \u0627\u0644\u0646\u0641\u0633\u064a<\/h2>\n\n\n<style>.kadence-column4674_0b076e-4a > .kt-inside-inner-col,.kadence-column4674_0b076e-4a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4674_0b076e-4a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4674_0b076e-4a > .kt-inside-inner-col{flex-direction:column;}.kadence-column4674_0b076e-4a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4674_0b076e-4a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4674_0b076e-4a{position:relative;}@media all and (max-width: 1024px){.kadence-column4674_0b076e-4a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4674_0b076e-4a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4674_0b076e-4a\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4674_98afd9-7f, .wp-block-kadence-advancedheading.kt-adv-heading4674_98afd9-7f[data-kb-block=\"kb-adv-heading4674_98afd9-7f\"]{margin-bottom:24px;font-style:normal;border-bottom:0px solid var(--global-palette6, #718096);}.wp-block-kadence-advancedheading.kt-adv-heading4674_98afd9-7f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4674_98afd9-7f[data-kb-block=\"kb-adv-heading4674_98afd9-7f\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4674_98afd9-7f img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4674_98afd9-7f[data-kb-block=\"kb-adv-heading4674_98afd9-7f\"] img.kb-inline-image{width:150px;vertical-align:baseline;}.wp-block-kadence-advancedheading.kt-adv-heading4674_98afd9-7f[data-kb-block=\"kb-adv-heading4674_98afd9-7f\"] a, .kt-adv-heading-link4674_98afd9-7f, .kt-adv-heading-link4674_98afd9-7f .kt-adv-heading4674_98afd9-7f[data-kb-block=\"kb-adv-heading4674_98afd9-7f\"]{color:var(--global-palette3, #1A202C);}.wp-block-kadence-advancedheading.kt-adv-heading4674_98afd9-7f[data-kb-block=\"kb-adv-heading4674_98afd9-7f\"] a:hover, .kt-adv-heading-link4674_98afd9-7f:hover, .kt-adv-heading-link4674_98afd9-7f:hover .kt-adv-heading4674_98afd9-7f[data-kb-block=\"kb-adv-heading4674_98afd9-7f\"]{color:var(--global-palette3, #1A202C);}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading4674_98afd9-7f, .wp-block-kadence-advancedheading.kt-adv-heading4674_98afd9-7f[data-kb-block=\"kb-adv-heading4674_98afd9-7f\"]{border-bottom:0px solid var(--global-palette6, #718096);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4674_98afd9-7f, .wp-block-kadence-advancedheading.kt-adv-heading4674_98afd9-7f[data-kb-block=\"kb-adv-heading4674_98afd9-7f\"]{border-bottom:0px solid var(--global-palette6, #718096);}}<\/style>\n<p class=\"kt-adv-heading4674_98afd9-7f wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4674_98afd9-7f\">\u0648\u0644\u062a\u0634\u062e\u064a\u0635 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628 \u0627\u0644\u0646\u0641\u0633\u064a \u0648\u0639\u0644\u0627\u062c\u0647 \u064a\u0639\u0645\u0644 \u0627\u0644\u0637\u0628\u064a\u0628 \u0627\u0644\u0646\u0641\u0633\u064a \u0639\u0644\u0649 \u0647\u0630\u0647 \u0627\u0644\u0645\u062d\u0627\u0648\u0631 \u0627\u0644\u062b\u0644\u0627\u062b:<\/p>\n\n\n\n<ol style=\"padding-left:18px\" class=\"wp-block-list weblist_ol_style_number weblist_ol_style_number_more_spaced\">\n<li>\u0627\u0644\u0641\u062d\u0635 \u0627\u0644\u0638\u0627\u0647\u0631\u064a:\u00a0 \u0648\u0641\u064a\u0647 \u064a\u0633\u062a\u0628\u0639\u062f \u0627\u0644\u0637\u0628\u064a\u0628 \u0648\u062c\u0648\u062f \u0623\u064a \u0623\u0645\u0631\u0627\u0636 \u062c\u0633\u062f\u064a\u0629 \u0642\u062f \u062a\u0643\u0648\u0646 \u0645\u0624\u062b\u0631\u0629 \u0639\u0644\u0649 \u0627\u0644\u062d\u0627\u0644\u0629 \u0627\u0644\u0646\u0641\u0633\u064a\u0629.<\/li>\n\n\n\n<li>\u00a0\u0627\u0644\u0641\u062d\u0635 \u0627\u0644\u0645\u0639\u0645\u0644\u0649: \u0648\u0630\u0644\u0643 \u0628\u0625\u062c\u0631\u0627\u0621 \u0627\u062e\u062a\u0628\u0627\u0631\u0627\u062a \u0645\u0639\u0645\u0644\u064a\u0629 \u0644\u062a\u0623\u0643\u064a\u062f \u062e\u0644\u0648 \u0627\u0644\u062c\u0633\u0645 \u0645\u0646 \u0622\u062b\u0627\u0631 \u0627\u0644\u0643\u062d\u0648\u0644 \u0648\u0627\u0644\u0645\u0648\u0627\u062f \u0627\u0644\u0645\u062e\u062f\u0631\u0629 \u0627\u0644\u062a\u064a \u062a\u0624\u062b\u0631 \u0639\u0644\u0649 \u0627\u0644\u062d\u0627\u0644\u0629 \u0627\u0644\u0646\u0641\u0633\u064a\u0629 \u0648\u0627\u0644\u0639\u0642\u0644\u064a\u0629 \u0644\u0644\u0634\u062e\u0635.<\/li>\n\n\n\n<li>\u00a0<a href=\"https:\/\/harborlondon.com\/ar\/%d9%83%d9%8a%d9%81-%d8%a7%d8%b9%d8%b1%d9%81-%d8%a7%d9%86%d9%8a-%d8%a7%d8%ad%d8%aa%d8%a7%d8%ac-%d8%b7%d8%a8%d9%8a%d8%a8-%d9%86%d9%81%d8%b3%d9%8a\/\">\u0627\u0644\u062a\u0642\u064a\u064a\u0645 \u0627\u0644\u0646\u0641\u0633\u064a<\/a>: \u0648\u0627\u0644\u0630\u064a \u064a\u0639\u062a\u0645\u062f \u0639\u0644\u0649 \u062c\u0644\u0633\u0627\u062a \u0627\u0644\u0645\u062d\u0627\u062f\u062b\u0629 \u0628\u064a\u0646 \u0627\u0644\u0637\u0628\u064a\u0628 \u0627\u0644\u0646\u0641\u0633\u064a \u0648\u0627\u0644\u0634\u062e\u0635 \u0644\u0645\u0639\u0631\u0641\u0629 \u0638\u0631\u0648\u0641\u0647 \u0627\u0644\u062d\u0627\u0644\u064a\u0629 \u0648\u0627\u0644\u0633\u0627\u0628\u0642\u0629 \u0648\u0623\u0641\u0643\u0627\u0631\u0647 \u0648\u0645\u0634\u0627\u0639\u0631\u0647 \u0648\u0633\u0644\u0648\u0643\u0647 \u062a\u062c\u0627\u0647 \u0627\u0644\u0623\u0634\u064a\u0627\u0621.<\/li>\n<\/ol>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column4674_e5237e-5e > .kt-inside-inner-col,.kadence-column4674_e5237e-5e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4674_e5237e-5e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4674_e5237e-5e > .kt-inside-inner-col{flex-direction:column;}.kadence-column4674_e5237e-5e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4674_e5237e-5e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4674_e5237e-5e{position:relative;}.kadence-column4674_e5237e-5e, .kt-inside-inner-col > .kadence-column4674_e5237e-5e:not(.specificity){margin-bottom:80px;}@media all and (max-width: 1024px){.kadence-column4674_e5237e-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column4674_e5237e-5e, .kt-inside-inner-col > .kadence-column4674_e5237e-5e:not(.specificity){margin-bottom:60px;}}@media all and (max-width: 767px){.kadence-column4674_e5237e-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4674_e5237e-5e single_article_single_content_section\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4674_dd1c3c-b9, .wp-block-kadence-advancedheading.kt-adv-heading4674_dd1c3c-b9[data-kb-block=\"kb-adv-heading4674_dd1c3c-b9\"]{margin-bottom:24px;font-size:32px;line-height:41px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4674_dd1c3c-b9 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4674_dd1c3c-b9[data-kb-block=\"kb-adv-heading4674_dd1c3c-b9\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4674_dd1c3c-b9 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4674_dd1c3c-b9[data-kb-block=\"kb-adv-heading4674_dd1c3c-b9\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4674_dd1c3c-b9, .wp-block-kadence-advancedheading.kt-adv-heading4674_dd1c3c-b9[data-kb-block=\"kb-adv-heading4674_dd1c3c-b9\"]{font-size:24px;line-height:29px;}}<\/style>\n<h2 class=\"kt-adv-heading4674_dd1c3c-b9 heading_h3 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4674_dd1c3c-b9\">\u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628 \u0627\u0644\u0646\u0641\u0633\u064a \u0648\u0639\u0644\u0627\u062c\u0647<\/h2>\n\n\n<style>.kadence-column4674_41e27f-78 > .kt-inside-inner-col,.kadence-column4674_41e27f-78 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4674_41e27f-78 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4674_41e27f-78 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4674_41e27f-78 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4674_41e27f-78 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4674_41e27f-78{position:relative;}@media all and (max-width: 1024px){.kadence-column4674_41e27f-78 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4674_41e27f-78 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4674_41e27f-78\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4674_895f7b-ab, .wp-block-kadence-advancedheading.kt-adv-heading4674_895f7b-ab[data-kb-block=\"kb-adv-heading4674_895f7b-ab\"]{margin-bottom:24px;font-style:normal;border-bottom:0px solid var(--global-palette6, #718096);}.wp-block-kadence-advancedheading.kt-adv-heading4674_895f7b-ab mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4674_895f7b-ab[data-kb-block=\"kb-adv-heading4674_895f7b-ab\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4674_895f7b-ab img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4674_895f7b-ab[data-kb-block=\"kb-adv-heading4674_895f7b-ab\"] img.kb-inline-image{width:150px;vertical-align:baseline;}.wp-block-kadence-advancedheading.kt-adv-heading4674_895f7b-ab[data-kb-block=\"kb-adv-heading4674_895f7b-ab\"] a, .kt-adv-heading-link4674_895f7b-ab, .kt-adv-heading-link4674_895f7b-ab .kt-adv-heading4674_895f7b-ab[data-kb-block=\"kb-adv-heading4674_895f7b-ab\"]{color:var(--global-palette3, #1A202C);}.wp-block-kadence-advancedheading.kt-adv-heading4674_895f7b-ab[data-kb-block=\"kb-adv-heading4674_895f7b-ab\"] a:hover, .kt-adv-heading-link4674_895f7b-ab:hover, .kt-adv-heading-link4674_895f7b-ab:hover .kt-adv-heading4674_895f7b-ab[data-kb-block=\"kb-adv-heading4674_895f7b-ab\"]{color:var(--global-palette3, #1A202C);}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading4674_895f7b-ab, .wp-block-kadence-advancedheading.kt-adv-heading4674_895f7b-ab[data-kb-block=\"kb-adv-heading4674_895f7b-ab\"]{border-bottom:0px solid var(--global-palette6, #718096);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4674_895f7b-ab, .wp-block-kadence-advancedheading.kt-adv-heading4674_895f7b-ab[data-kb-block=\"kb-adv-heading4674_895f7b-ab\"]{border-bottom:0px solid var(--global-palette6, #718096);}}<\/style>\n<p class=\"kt-adv-heading4674_895f7b-ab wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4674_895f7b-ab\">\u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629 \u0648\u0639\u0644\u0627\u062c\u0647\u0627 \u062a\u062d\u062a\u0627\u062c \u0643\u0645\u0627 \u0630\u0643\u0631\u0646\u0627 \u0633\u0627\u0628\u0642\u0627\u064b \u0627\u0644\u0649 \u0627\u062c\u062a\u0647\u0627\u062f \u0648\u062f\u0642\u0647 \u0641\u064a \u0627\u0644\u062a\u0634\u062e\u064a\u0635\u061b \u0646\u0638\u0631\u0627\u064b \u0644\u062a\u062f\u0627\u062e\u0644 \u0623\u0639\u0631\u0627\u0636 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629 \u0648\u062a\u0634\u0627\u0628\u0647\u0647\u0627 \u0641\u064a \u0623\u062d\u064a\u0627\u0646 \u0643\u062b\u064a\u0631\u0629\u060c \u0648\u0639\u0644\u0649 \u0623\u0633\u0627\u0633 \u0627\u0644\u062a\u0634\u062e\u064a\u0635 \u062a\u064f\u0648\u0636\u0639 \u062e\u0637\u0629 \u0627\u0644\u0639\u0644\u0627\u062c\u00a0 \u0644\u0643\u0644 \u0639\u0645\u064a\u0644 \u0639\u0644\u0649 \u062d\u062f\u0629\u060c \u0625\u0644\u0627 \u0623\u0646\u0647 \u0628\u0634\u0643\u0644 \u0639\u0627\u0645 \u062a\u0631\u062a\u0643\u0632 \u0645\u062d\u0627\u0648\u0631 \u0627\u0644\u0639\u0644\u0627\u062c \u0627\u0644\u0646\u0641\u0633\u064a \u0639\u0644\u0649 \u0639\u062f\u0629 \u0646\u0642\u0627\u0637 \u0623\u0633\u0627\u0633\u064a\u0629:<\/p>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items4674_93079f-c5:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items4674_93079f-c5 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-bottom:24px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items4674_93079f-c5 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items4674_93079f-c5 .kb-svg-icon-wrap{font-size:4px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items4674_93079f-c5 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-left:8px;}.kt-svg-icon-list-items4674_93079f-c5 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}@media all and (max-width: 767px){.wp-block-kadence-iconlist.kt-svg-icon-list-items4674_93079f-c5 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){padding-left:10px;}}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items4674_93079f-c5 kt-svg-icon-list-columns-1 alignnone kt-list-icon-aligntop web_icon_bullets_list\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-4674_c4a642-f2 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-4674_c4a642-f2\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_circle kt-svg-icon-list-single\"><svg viewBox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">\u0627\u0644\u0639\u0644\u0627\u062c \u0627\u0644\u062f\u0648\u0627\u0626\u064a:\u00a0 \u0648\u0641\u064a\u0647 \u062a\u0633\u062a\u062e\u062f\u0645\u00a0 \u0627\u0644\u0639\u0642\u0627\u0642\u064a\u0631 \u0627\u0644\u0637\u0628\u064a\u0629 \u0645\u062b\u0644 \u0639\u0642\u0627\u0642\u064a\u0631 \u062a\u062b\u0628\u064a\u062a \u0627\u0644\u062d\u0627\u0644\u0629 \u0627\u0644\u0645\u0632\u0627\u062c\u064a\u0629\u060c \u0648<a href=\"https:\/\/www.nhs.uk\/conditions\/antidepressants\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u0627\u0644\u0639\u0642\u0627\u0642\u064a\u0631 \u0627\u0644\u0645\u0636\u0627\u062f\u0629 \u0644\u0644\u0627\u0643\u062a\u0626\u0627\u0628<\/a>.<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-4674_fac4d6-29 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-4674_fac4d6-29\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_circle kt-svg-icon-list-single\"><svg viewBox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">\u0627\u0644\u0639\u0644\u0627\u062c \u0627\u0644\u0646\u0641\u0633\u064a: \u0639\u0646 \u0637\u0631\u064a\u0642 \u0627\u0644\u062c\u0644\u0633\u0627\u062a \u0627\u0644\u0645\u0628\u0627\u0634\u0631\u0629 \u0645\u0639 \u0627\u0644\u0637\u0628\u064a\u0628 \u0627\u0644\u0646\u0641\u0633\u064a.<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-4674_f23248-0310 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-4674_f23248-0310\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_circle kt-svg-icon-list-single\"><svg viewBox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">\u0627\u0644\u0631\u064a\u0627\u0636\u0629 \u0648\u0627\u0644\u064a\u0648\u062c\u0627.<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading4674_61bfaa-40, .wp-block-kadence-advancedheading.kt-adv-heading4674_61bfaa-40[data-kb-block=\"kb-adv-heading4674_61bfaa-40\"]{margin-bottom:24px;font-style:normal;border-bottom:0px solid var(--global-palette6, #718096);}.wp-block-kadence-advancedheading.kt-adv-heading4674_61bfaa-40 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4674_61bfaa-40[data-kb-block=\"kb-adv-heading4674_61bfaa-40\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4674_61bfaa-40 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4674_61bfaa-40[data-kb-block=\"kb-adv-heading4674_61bfaa-40\"] img.kb-inline-image{width:150px;vertical-align:baseline;}.wp-block-kadence-advancedheading.kt-adv-heading4674_61bfaa-40[data-kb-block=\"kb-adv-heading4674_61bfaa-40\"] a, .kt-adv-heading-link4674_61bfaa-40, .kt-adv-heading-link4674_61bfaa-40 .kt-adv-heading4674_61bfaa-40[data-kb-block=\"kb-adv-heading4674_61bfaa-40\"]{color:var(--global-palette3, #1A202C);}.wp-block-kadence-advancedheading.kt-adv-heading4674_61bfaa-40[data-kb-block=\"kb-adv-heading4674_61bfaa-40\"] a:hover, .kt-adv-heading-link4674_61bfaa-40:hover, .kt-adv-heading-link4674_61bfaa-40:hover .kt-adv-heading4674_61bfaa-40[data-kb-block=\"kb-adv-heading4674_61bfaa-40\"]{color:var(--global-palette3, #1A202C);}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading4674_61bfaa-40, .wp-block-kadence-advancedheading.kt-adv-heading4674_61bfaa-40[data-kb-block=\"kb-adv-heading4674_61bfaa-40\"]{border-bottom:0px solid var(--global-palette6, #718096);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4674_61bfaa-40, .wp-block-kadence-advancedheading.kt-adv-heading4674_61bfaa-40[data-kb-block=\"kb-adv-heading4674_61bfaa-40\"]{border-bottom:0px solid var(--global-palette6, #718096);}}<\/style>\n<p class=\"kt-adv-heading4674_61bfaa-40 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4674_61bfaa-40\">\u0628\u0627\u0644\u0637\u0628\u0639 \u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0623\u0646\u0648\u0627\u0639\u00a0<a href=\"\/ar\/%d8%b9%d9%84%d8%a7%d8%ac-%d8%a7%d9%84%d8%a7%d9%85%d8%b1%d8%a7%d8%b6-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629<\/a>\u00a0\u0627\u0644\u062a\u064a \u0644\u0645 \u064a\u062a\u0633\u0639 \u0627\u0644\u0645\u062c\u0627\u0644 \u0644\u0630\u0643\u0631\u0647\u0627 \u0625\u0644\u0627 \u0623\u0646 \u0645\u0627 \u062a\u0645 \u0630\u0643\u0631\u0647 \u0645\u0646 \u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629 \u0648\u0637\u0631\u0642 \u0639\u0644\u0627\u062c\u0647\u0627 \u062a\u0639\u062f \u0647\u064a \u0627\u0644\u0623\u0643\u062b\u0631 \u0645\u0646 \u062d\u064a\u062b \u0627\u0644\u0623\u0647\u0645\u064a\u0629 \u0648\u0627\u0644\u0634\u064a\u0648\u0639.<br><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading4674_c63355-f8, .wp-block-kadence-advancedheading.kt-adv-heading4674_c63355-f8[data-kb-block=\"kb-adv-heading4674_c63355-f8\"]{margin-bottom:24px;font-style:normal;border-bottom:0px solid var(--global-palette6, #718096);}.wp-block-kadence-advancedheading.kt-adv-heading4674_c63355-f8 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4674_c63355-f8[data-kb-block=\"kb-adv-heading4674_c63355-f8\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4674_c63355-f8 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4674_c63355-f8[data-kb-block=\"kb-adv-heading4674_c63355-f8\"] img.kb-inline-image{width:150px;vertical-align:baseline;}.wp-block-kadence-advancedheading.kt-adv-heading4674_c63355-f8[data-kb-block=\"kb-adv-heading4674_c63355-f8\"] a, .kt-adv-heading-link4674_c63355-f8, .kt-adv-heading-link4674_c63355-f8 .kt-adv-heading4674_c63355-f8[data-kb-block=\"kb-adv-heading4674_c63355-f8\"]{color:var(--global-palette3, #1A202C);}.wp-block-kadence-advancedheading.kt-adv-heading4674_c63355-f8[data-kb-block=\"kb-adv-heading4674_c63355-f8\"] a:hover, .kt-adv-heading-link4674_c63355-f8:hover, .kt-adv-heading-link4674_c63355-f8:hover .kt-adv-heading4674_c63355-f8[data-kb-block=\"kb-adv-heading4674_c63355-f8\"]{color:var(--global-palette3, #1A202C);}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading4674_c63355-f8, .wp-block-kadence-advancedheading.kt-adv-heading4674_c63355-f8[data-kb-block=\"kb-adv-heading4674_c63355-f8\"]{border-bottom:0px solid var(--global-palette6, #718096);}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4674_c63355-f8, .wp-block-kadence-advancedheading.kt-adv-heading4674_c63355-f8[data-kb-block=\"kb-adv-heading4674_c63355-f8\"]{border-bottom:0px solid var(--global-palette6, #718096);}}<\/style>\n<p class=\"kt-adv-heading4674_c63355-f8 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4674_c63355-f8\"><a href=\"\/ar\/%d8%a7%d8%aa%d8%b5%d9%84-%d8%a8%d9%86%d8%a7\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u062a\u0648\u0627\u0635\u0644 \u0645\u0639\u0646\u0627<\/a>\u00a0\u0627\u0644\u0622\u0646 \u0641\u064a \u0647\u0627\u0631\u0628\u0648\u0631 \u0644\u062a\u0628\u062f\u0623 \u0631\u062d\u0644\u062a\u0643 \u0646\u062d\u0648 \u0627\u0644\u062a\u0639\u0627\u0641\u064a.<\/p>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0628\u0630\u0644 \u0639\u0644\u0645\u0627\u0621 \u0627\u0644\u0646\u0641\u0633 \u0627\u0644\u0643\u062b\u064a\u0631 \u0645\u0646 \u0627\u0644\u0648\u0642\u062a \u0648\u0627\u0644\u062c\u0647\u062f \u0639\u0644\u0649 \u0645\u062f\u0627\u0631 \u0627\u0644\u0633\u0646\u0648\u0627\u062a \u0627\u0644\u0633\u0627\u0628\u0642\u0629 \u0644\u0644\u062a\u0639\u0631\u0641 \u0639\u0644\u0649 \u062e\u0641\u0627\u064a\u0627 \u0627\u0644\u0646\u0641\u0633 \u0627\u0644\u0628\u0634\u0631\u064a\u0629\u061b \u0630\u0644\u0643 \u0623\u0646 \u0641\u0647\u0645 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629 \u0648\u0639\u0644\u0627\u062c\u0647\u0627 \u0645\u0639\u0642\u062f \u0648\u064a\u062d\u062a\u0627\u062c \u0627\u0644\u0649 \u0627\u0644\u0625\u0644\u0645\u0627\u0645 \u0628\u062c\u0645\u064a\u0639 \u0627\u0644\u0638\u0631\u0648\u0641 \u0627\u0644\u062a\u064a \u062a\u0639\u0631\u0636 \u0644\u0647\u0627 \u0627\u0644\u0634\u062e\u0635 \u0627\u0644\u0645\u0635\u0627\u0628 \u0628\u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628 \u0627\u0644\u0646\u0641\u0633\u064a\u060c \u0644\u064a\u0633\u062a \u0627\u0644\u0638\u0631\u0648\u0641 \u0627\u0644\u062d\u0627\u0644\u064a\u0629 \u0641\u0642\u0637 \u0648\u0627\u0646\u0645\u0627 \u062a\u0635\u0644 \u0627\u0644\u062d\u0627\u062c\u0629 \u0644\u0645\u0639\u0631\u0641\u0629 \u0638\u0631\u0648\u0641 \u0627\u0644\u0646\u0634\u0623\u0629 \u0627\u0644\u062d\u064a\u0627\u062a\u064a\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0634\u062e\u0635\u061b \u0648\u0645\u0639\u0631\u0641\u0629 \u0637\u0628\u064a\u0639\u0629 \u0634\u062e\u0635\u064a\u062a\u0647 \u061b\u0648\u0643\u0644\u0645\u0627 \u0643\u0627\u0646\u062a \u0627\u0644\u0645\u0639\u0644\u0648\u0645\u0627\u062a \u0648\u0641\u064a\u0631\u0629&#8230;<\/p>\n","protected":false},"author":8,"featured_media":4675,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_joinchat":[],"footnotes":""},"categories":[119],"tags":[227,228,229],"class_list":["post-4674","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-119","tag-227","tag-228","tag-229"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629 \u0648\u0639\u0644\u0627\u062c\u0647\u0627 - \u0623\u0647\u0645 \u0627\u0646\u0648\u0627\u0639 \u0627\u0644\u0627\u0645\u0631\u0627\u0636 \u0627\u0644\u0646\u0641\u0633\u064a\u0629<\/title>\n<meta name=\"description\" content=\"\u062a\u0639\u0631\u0641 \u0639\u0644\u0649 \u0623\u0647\u0645 \u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629 \u0648\u0639\u0644\u0627\u062c\u0647\u0627 \u0648\u0637\u0631\u0642 \u0627\u0644\u0648\u0642\u0627\u064a\u0629 \u0645\u0646\u0647\u0627 \u0641\u064a \u0647\u0630\u0627 \u0627\u0644\u0645\u0642\u0627\u0644 \u0639\u0644\u0649 \u0645\u0648\u0642\u0639 \u0647\u0627\u0631\u0628\u0648\u0631 \u0645\u0631\u0643\u0632 \u0641\u0627\u062e\u0631 \u0644\u0639\u0644\u0627\u062c \u0627\u0644\u0625\u062f\u0645\u0627\u0646.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/harborlondon.com\/ar\/%d8%a7%d9%86%d9%88%d8%a7%d8%b9-%d8%a7%d9%84%d8%a7%d8%b6%d8%b7%d8%b1%d8%a7%d8%a8%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9-%d9%88%d8%b9%d9%84%d8%a7%d8%ac%d9%87%d8%a7\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629 \u0648\u0639\u0644\u0627\u062c\u0647\u0627 - \u0623\u0647\u0645 \u0627\u0646\u0648\u0627\u0639 \u0627\u0644\u0627\u0645\u0631\u0627\u0636 \u0627\u0644\u0646\u0641\u0633\u064a\u0629\" \/>\n<meta property=\"og:description\" content=\"\u062a\u0639\u0631\u0641 \u0639\u0644\u0649 \u0623\u0647\u0645 \u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629 \u0648\u0639\u0644\u0627\u062c\u0647\u0627 \u0648\u0637\u0631\u0642 \u0627\u0644\u0648\u0642\u0627\u064a\u0629 \u0645\u0646\u0647\u0627 \u0641\u064a \u0647\u0630\u0627 \u0627\u0644\u0645\u0642\u0627\u0644 \u0639\u0644\u0649 \u0645\u0648\u0642\u0639 \u0647\u0627\u0631\u0628\u0648\u0631 \u0645\u0631\u0643\u0632 \u0641\u0627\u062e\u0631 \u0644\u0639\u0644\u0627\u062c \u0627\u0644\u0625\u062f\u0645\u0627\u0646.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/harborlondon.com\/ar\/%d8%a7%d9%86%d9%88%d8%a7%d8%b9-%d8%a7%d9%84%d8%a7%d8%b6%d8%b7%d8%b1%d8%a7%d8%a8%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9-%d9%88%d8%b9%d9%84%d8%a7%d8%ac%d9%87%d8%a7\/\" \/>\n<meta property=\"og:site_name\" content=\"Harbor London\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HarborLondon\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-15T10:04:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-05T14:54:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/harborlondon.com\/wp-content\/uploads\/2026\/01\/\u0627\u0644\u0646\u0641\u0633\u064a\u0629-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dr. Farrukh Alam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0643\u064f\u062a\u0628 \u0628\u0648\u0627\u0633\u0637\u0629\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u062f. \u0641\u0627\u0631\u0648\u0642 \u0639\u0644\u0627\u0645\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 \u062f\u0642\u0627\u0626\u0642\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/harborlondon.com\\\/ar\\\/%d8%a7%d9%86%d9%88%d8%a7%d8%b9-%d8%a7%d9%84%d8%a7%d8%b6%d8%b7%d8%b1%d8%a7%d8%a8%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9-%d9%88%d8%b9%d9%84%d8%a7%d8%ac%d9%87%d8%a7\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/harborlondon.com\\\/ar\\\/%d8%a7%d9%86%d9%88%d8%a7%d8%b9-%d8%a7%d9%84%d8%a7%d8%b6%d8%b7%d8%b1%d8%a7%d8%a8%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9-%d9%88%d8%b9%d9%84%d8%a7%d8%ac%d9%87%d8%a7\\\/\"},\"author\":{\"name\":\"Dr. Farrukh Alam\",\"@id\":\"https:\\\/\\\/harborlondon.com\\\/ar\\\/#\\\/schema\\\/person\\\/c2669c495d1f1da3688092faf68af41f\"},\"headline\":\"\u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629 \u0648\u0639\u0644\u0627\u062c\u0647\u0627\",\"datePublished\":\"2024-12-15T10:04:00+00:00\",\"dateModified\":\"2026-03-05T14:54:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/harborlondon.com\\\/ar\\\/%d8%a7%d9%86%d9%88%d8%a7%d8%b9-%d8%a7%d9%84%d8%a7%d8%b6%d8%b7%d8%b1%d8%a7%d8%a8%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9-%d9%88%d8%b9%d9%84%d8%a7%d8%ac%d9%87%d8%a7\\\/\"},\"wordCount\":1,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/harborlondon.com\\\/ar\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/harborlondon.com\\\/ar\\\/%d8%a7%d9%86%d9%88%d8%a7%d8%b9-%d8%a7%d9%84%d8%a7%d8%b6%d8%b7%d8%b1%d8%a7%d8%a8%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9-%d9%88%d8%b9%d9%84%d8%a7%d8%ac%d9%87%d8%a7\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/harborlondon.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/\u0627\u0644\u0646\u0641\u0633\u064a\u0629-scaled-1.jpg\",\"keywords\":[\"\u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628 \u0627\u0644\u0646\u0641\u0633\u064a \u0648\u0639\u0644\u0627\u062c\u0647\",\"\u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629 \u0648\u0639\u0644\u0627\u062c\u0647\u0627\",\"\u0627\u0646\u0648\u0627\u0639 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629\"],\"articleSection\":[\"\u0627\u0644\u0623\u0645\u0631\u0627\u0636 \u0627\u0644\u0646\u0641\u0633\u064a\u0629\"],\"inLanguage\":\"ar\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/harborlondon.com\\\/ar\\\/%d8%a7%d9%86%d9%88%d8%a7%d8%b9-%d8%a7%d9%84%d8%a7%d8%b6%d8%b7%d8%b1%d8%a7%d8%a8%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9-%d9%88%d8%b9%d9%84%d8%a7%d8%ac%d9%87%d8%a7\\\/\",\"url\":\"https:\\\/\\\/harborlondon.com\\\/ar\\\/%d8%a7%d9%86%d9%88%d8%a7%d8%b9-%d8%a7%d9%84%d8%a7%d8%b6%d8%b7%d8%b1%d8%a7%d8%a8%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9-%d9%88%d8%b9%d9%84%d8%a7%d8%ac%d9%87%d8%a7\\\/\",\"name\":\"\u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629 \u0648\u0639\u0644\u0627\u062c\u0647\u0627 - \u0623\u0647\u0645 \u0627\u0646\u0648\u0627\u0639 \u0627\u0644\u0627\u0645\u0631\u0627\u0636 \u0627\u0644\u0646\u0641\u0633\u064a\u0629\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/harborlondon.com\\\/ar\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/harborlondon.com\\\/ar\\\/%d8%a7%d9%86%d9%88%d8%a7%d8%b9-%d8%a7%d9%84%d8%a7%d8%b6%d8%b7%d8%b1%d8%a7%d8%a8%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9-%d9%88%d8%b9%d9%84%d8%a7%d8%ac%d9%87%d8%a7\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/harborlondon.com\\\/ar\\\/%d8%a7%d9%86%d9%88%d8%a7%d8%b9-%d8%a7%d9%84%d8%a7%d8%b6%d8%b7%d8%b1%d8%a7%d8%a8%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9-%d9%88%d8%b9%d9%84%d8%a7%d8%ac%d9%87%d8%a7\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/harborlondon.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/\u0627\u0644\u0646\u0641\u0633\u064a\u0629-scaled-1.jpg\",\"datePublished\":\"2024-12-15T10:04:00+00:00\",\"dateModified\":\"2026-03-05T14:54:55+00:00\",\"description\":\"\u062a\u0639\u0631\u0641 \u0639\u0644\u0649 \u0623\u0647\u0645 \u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629 \u0648\u0639\u0644\u0627\u062c\u0647\u0627 \u0648\u0637\u0631\u0642 \u0627\u0644\u0648\u0642\u0627\u064a\u0629 \u0645\u0646\u0647\u0627 \u0641\u064a \u0647\u0630\u0627 \u0627\u0644\u0645\u0642\u0627\u0644 \u0639\u0644\u0649 \u0645\u0648\u0642\u0639 \u0647\u0627\u0631\u0628\u0648\u0631 \u0645\u0631\u0643\u0632 \u0641\u0627\u062e\u0631 \u0644\u0639\u0644\u0627\u062c \u0627\u0644\u0625\u062f\u0645\u0627\u0646.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/harborlondon.com\\\/ar\\\/%d8%a7%d9%86%d9%88%d8%a7%d8%b9-%d8%a7%d9%84%d8%a7%d8%b6%d8%b7%d8%b1%d8%a7%d8%a8%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9-%d9%88%d8%b9%d9%84%d8%a7%d8%ac%d9%87%d8%a7\\\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/harborlondon.com\\\/ar\\\/%d8%a7%d9%86%d9%88%d8%a7%d8%b9-%d8%a7%d9%84%d8%a7%d8%b6%d8%b7%d8%b1%d8%a7%d8%a8%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9-%d9%88%d8%b9%d9%84%d8%a7%d8%ac%d9%87%d8%a7\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/harborlondon.com\\\/ar\\\/%d8%a7%d9%86%d9%88%d8%a7%d8%b9-%d8%a7%d9%84%d8%a7%d8%b6%d8%b7%d8%b1%d8%a7%d8%a8%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9-%d9%88%d8%b9%d9%84%d8%a7%d8%ac%d9%87%d8%a7\\\/#primaryimage\",\"url\":\"https:\\\/\\\/harborlondon.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/\u0627\u0644\u0646\u0641\u0633\u064a\u0629-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/harborlondon.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/\u0627\u0644\u0646\u0641\u0633\u064a\u0629-scaled-1.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/harborlondon.com\\\/ar\\\/%d8%a7%d9%86%d9%88%d8%a7%d8%b9-%d8%a7%d9%84%d8%a7%d8%b6%d8%b7%d8%b1%d8%a7%d8%a8%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9-%d9%88%d8%b9%d9%84%d8%a7%d8%ac%d9%87%d8%a7\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/harborlondon.com\\\/ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629 \u0648\u0639\u0644\u0627\u062c\u0647\u0627\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/harborlondon.com\\\/ar\\\/#website\",\"url\":\"https:\\\/\\\/harborlondon.com\\\/ar\\\/\",\"name\":\"Harbor London\",\"description\":\"Empathy in every stride. Expertise in every solution.\",\"publisher\":{\"@id\":\"https:\\\/\\\/harborlondon.com\\\/ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/harborlondon.com\\\/ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/harborlondon.com\\\/ar\\\/#organization\",\"name\":\"Harbor London\",\"url\":\"https:\\\/\\\/harborlondon.com\\\/ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/harborlondon.com\\\/ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/harborlondon.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/favicon.png.webp\",\"contentUrl\":\"https:\\\/\\\/harborlondon.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/favicon.png.webp\",\"width\":264,\"height\":264,\"caption\":\"Harbor London\"},\"image\":{\"@id\":\"https:\\\/\\\/harborlondon.com\\\/ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/HarborLondon\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/harborlondon\\\/\",\"https:\\\/\\\/www.instagram.com\\\/harbor_london\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/harborlondon.com\\\/ar\\\/#\\\/schema\\\/person\\\/c2669c495d1f1da3688092faf68af41f\",\"name\":\"Dr. Farrukh Alam\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5a609088fcc45c198040570c8f43a4c24eef5d0b7923a4b0942d193bb225dc9c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5a609088fcc45c198040570c8f43a4c24eef5d0b7923a4b0942d193bb225dc9c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5a609088fcc45c198040570c8f43a4c24eef5d0b7923a4b0942d193bb225dc9c?s=96&d=mm&r=g\",\"caption\":\"Dr. Farrukh Alam\"},\"url\":\"https:\\\/\\\/harborlondon.com\\\/ar\\\/author\\\/dr-farrukh-alam\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629 \u0648\u0639\u0644\u0627\u062c\u0647\u0627 - \u0623\u0647\u0645 \u0627\u0646\u0648\u0627\u0639 \u0627\u0644\u0627\u0645\u0631\u0627\u0636 \u0627\u0644\u0646\u0641\u0633\u064a\u0629","description":"\u062a\u0639\u0631\u0641 \u0639\u0644\u0649 \u0623\u0647\u0645 \u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629 \u0648\u0639\u0644\u0627\u062c\u0647\u0627 \u0648\u0637\u0631\u0642 \u0627\u0644\u0648\u0642\u0627\u064a\u0629 \u0645\u0646\u0647\u0627 \u0641\u064a \u0647\u0630\u0627 \u0627\u0644\u0645\u0642\u0627\u0644 \u0639\u0644\u0649 \u0645\u0648\u0642\u0639 \u0647\u0627\u0631\u0628\u0648\u0631 \u0645\u0631\u0643\u0632 \u0641\u0627\u062e\u0631 \u0644\u0639\u0644\u0627\u062c \u0627\u0644\u0625\u062f\u0645\u0627\u0646.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/harborlondon.com\/ar\/%d8%a7%d9%86%d9%88%d8%a7%d8%b9-%d8%a7%d9%84%d8%a7%d8%b6%d8%b7%d8%b1%d8%a7%d8%a8%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9-%d9%88%d8%b9%d9%84%d8%a7%d8%ac%d9%87%d8%a7\/","og_locale":"ar_AR","og_type":"article","og_title":"\u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629 \u0648\u0639\u0644\u0627\u062c\u0647\u0627 - \u0623\u0647\u0645 \u0627\u0646\u0648\u0627\u0639 \u0627\u0644\u0627\u0645\u0631\u0627\u0636 \u0627\u0644\u0646\u0641\u0633\u064a\u0629","og_description":"\u062a\u0639\u0631\u0641 \u0639\u0644\u0649 \u0623\u0647\u0645 \u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629 \u0648\u0639\u0644\u0627\u062c\u0647\u0627 \u0648\u0637\u0631\u0642 \u0627\u0644\u0648\u0642\u0627\u064a\u0629 \u0645\u0646\u0647\u0627 \u0641\u064a \u0647\u0630\u0627 \u0627\u0644\u0645\u0642\u0627\u0644 \u0639\u0644\u0649 \u0645\u0648\u0642\u0639 \u0647\u0627\u0631\u0628\u0648\u0631 \u0645\u0631\u0643\u0632 \u0641\u0627\u062e\u0631 \u0644\u0639\u0644\u0627\u062c \u0627\u0644\u0625\u062f\u0645\u0627\u0646.","og_url":"https:\/\/harborlondon.com\/ar\/%d8%a7%d9%86%d9%88%d8%a7%d8%b9-%d8%a7%d9%84%d8%a7%d8%b6%d8%b7%d8%b1%d8%a7%d8%a8%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9-%d9%88%d8%b9%d9%84%d8%a7%d8%ac%d9%87%d8%a7\/","og_site_name":"Harbor London","article_publisher":"https:\/\/www.facebook.com\/HarborLondon\/","article_published_time":"2024-12-15T10:04:00+00:00","article_modified_time":"2026-03-05T14:54:55+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/harborlondon.com\/wp-content\/uploads\/2026\/01\/\u0627\u0644\u0646\u0641\u0633\u064a\u0629-scaled-1.jpg","type":"image\/jpeg"}],"author":"Dr. Farrukh Alam","twitter_card":"summary_large_image","twitter_misc":{"\u0643\u064f\u062a\u0628 \u0628\u0648\u0627\u0633\u0637\u0629":"\u062f. \u0641\u0627\u0631\u0648\u0642 \u0639\u0644\u0627\u0645","\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631":"4 \u062f\u0642\u0627\u0626\u0642"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/harborlondon.com\/ar\/%d8%a7%d9%86%d9%88%d8%a7%d8%b9-%d8%a7%d9%84%d8%a7%d8%b6%d8%b7%d8%b1%d8%a7%d8%a8%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9-%d9%88%d8%b9%d9%84%d8%a7%d8%ac%d9%87%d8%a7\/#article","isPartOf":{"@id":"https:\/\/harborlondon.com\/ar\/%d8%a7%d9%86%d9%88%d8%a7%d8%b9-%d8%a7%d9%84%d8%a7%d8%b6%d8%b7%d8%b1%d8%a7%d8%a8%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9-%d9%88%d8%b9%d9%84%d8%a7%d8%ac%d9%87%d8%a7\/"},"author":{"name":"Dr. Farrukh Alam","@id":"https:\/\/harborlondon.com\/ar\/#\/schema\/person\/c2669c495d1f1da3688092faf68af41f"},"headline":"\u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629 \u0648\u0639\u0644\u0627\u062c\u0647\u0627","datePublished":"2024-12-15T10:04:00+00:00","dateModified":"2026-03-05T14:54:55+00:00","mainEntityOfPage":{"@id":"https:\/\/harborlondon.com\/ar\/%d8%a7%d9%86%d9%88%d8%a7%d8%b9-%d8%a7%d9%84%d8%a7%d8%b6%d8%b7%d8%b1%d8%a7%d8%a8%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9-%d9%88%d8%b9%d9%84%d8%a7%d8%ac%d9%87%d8%a7\/"},"wordCount":1,"commentCount":0,"publisher":{"@id":"https:\/\/harborlondon.com\/ar\/#organization"},"image":{"@id":"https:\/\/harborlondon.com\/ar\/%d8%a7%d9%86%d9%88%d8%a7%d8%b9-%d8%a7%d9%84%d8%a7%d8%b6%d8%b7%d8%b1%d8%a7%d8%a8%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9-%d9%88%d8%b9%d9%84%d8%a7%d8%ac%d9%87%d8%a7\/#primaryimage"},"thumbnailUrl":"https:\/\/harborlondon.com\/wp-content\/uploads\/2026\/01\/\u0627\u0644\u0646\u0641\u0633\u064a\u0629-scaled-1.jpg","keywords":["\u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628 \u0627\u0644\u0646\u0641\u0633\u064a \u0648\u0639\u0644\u0627\u062c\u0647","\u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629 \u0648\u0639\u0644\u0627\u062c\u0647\u0627","\u0627\u0646\u0648\u0627\u0639 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629"],"articleSection":["\u0627\u0644\u0623\u0645\u0631\u0627\u0636 \u0627\u0644\u0646\u0641\u0633\u064a\u0629"],"inLanguage":"ar"},{"@type":"WebPage","@id":"https:\/\/harborlondon.com\/ar\/%d8%a7%d9%86%d9%88%d8%a7%d8%b9-%d8%a7%d9%84%d8%a7%d8%b6%d8%b7%d8%b1%d8%a7%d8%a8%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9-%d9%88%d8%b9%d9%84%d8%a7%d8%ac%d9%87%d8%a7\/","url":"https:\/\/harborlondon.com\/ar\/%d8%a7%d9%86%d9%88%d8%a7%d8%b9-%d8%a7%d9%84%d8%a7%d8%b6%d8%b7%d8%b1%d8%a7%d8%a8%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9-%d9%88%d8%b9%d9%84%d8%a7%d8%ac%d9%87%d8%a7\/","name":"\u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629 \u0648\u0639\u0644\u0627\u062c\u0647\u0627 - \u0623\u0647\u0645 \u0627\u0646\u0648\u0627\u0639 \u0627\u0644\u0627\u0645\u0631\u0627\u0636 \u0627\u0644\u0646\u0641\u0633\u064a\u0629","isPartOf":{"@id":"https:\/\/harborlondon.com\/ar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/harborlondon.com\/ar\/%d8%a7%d9%86%d9%88%d8%a7%d8%b9-%d8%a7%d9%84%d8%a7%d8%b6%d8%b7%d8%b1%d8%a7%d8%a8%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9-%d9%88%d8%b9%d9%84%d8%a7%d8%ac%d9%87%d8%a7\/#primaryimage"},"image":{"@id":"https:\/\/harborlondon.com\/ar\/%d8%a7%d9%86%d9%88%d8%a7%d8%b9-%d8%a7%d9%84%d8%a7%d8%b6%d8%b7%d8%b1%d8%a7%d8%a8%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9-%d9%88%d8%b9%d9%84%d8%a7%d8%ac%d9%87%d8%a7\/#primaryimage"},"thumbnailUrl":"https:\/\/harborlondon.com\/wp-content\/uploads\/2026\/01\/\u0627\u0644\u0646\u0641\u0633\u064a\u0629-scaled-1.jpg","datePublished":"2024-12-15T10:04:00+00:00","dateModified":"2026-03-05T14:54:55+00:00","description":"\u062a\u0639\u0631\u0641 \u0639\u0644\u0649 \u0623\u0647\u0645 \u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629 \u0648\u0639\u0644\u0627\u062c\u0647\u0627 \u0648\u0637\u0631\u0642 \u0627\u0644\u0648\u0642\u0627\u064a\u0629 \u0645\u0646\u0647\u0627 \u0641\u064a \u0647\u0630\u0627 \u0627\u0644\u0645\u0642\u0627\u0644 \u0639\u0644\u0649 \u0645\u0648\u0642\u0639 \u0647\u0627\u0631\u0628\u0648\u0631 \u0645\u0631\u0643\u0632 \u0641\u0627\u062e\u0631 \u0644\u0639\u0644\u0627\u062c \u0627\u0644\u0625\u062f\u0645\u0627\u0646.","breadcrumb":{"@id":"https:\/\/harborlondon.com\/ar\/%d8%a7%d9%86%d9%88%d8%a7%d8%b9-%d8%a7%d9%84%d8%a7%d8%b6%d8%b7%d8%b1%d8%a7%d8%a8%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9-%d9%88%d8%b9%d9%84%d8%a7%d8%ac%d9%87%d8%a7\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/harborlondon.com\/ar\/%d8%a7%d9%86%d9%88%d8%a7%d8%b9-%d8%a7%d9%84%d8%a7%d8%b6%d8%b7%d8%b1%d8%a7%d8%a8%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9-%d9%88%d8%b9%d9%84%d8%a7%d8%ac%d9%87%d8%a7\/"]}]},{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/harborlondon.com\/ar\/%d8%a7%d9%86%d9%88%d8%a7%d8%b9-%d8%a7%d9%84%d8%a7%d8%b6%d8%b7%d8%b1%d8%a7%d8%a8%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9-%d9%88%d8%b9%d9%84%d8%a7%d8%ac%d9%87%d8%a7\/#primaryimage","url":"https:\/\/harborlondon.com\/wp-content\/uploads\/2026\/01\/\u0627\u0644\u0646\u0641\u0633\u064a\u0629-scaled-1.jpg","contentUrl":"https:\/\/harborlondon.com\/wp-content\/uploads\/2026\/01\/\u0627\u0644\u0646\u0641\u0633\u064a\u0629-scaled-1.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/harborlondon.com\/ar\/%d8%a7%d9%86%d9%88%d8%a7%d8%b9-%d8%a7%d9%84%d8%a7%d8%b6%d8%b7%d8%b1%d8%a7%d8%a8%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9-%d9%88%d8%b9%d9%84%d8%a7%d8%ac%d9%87%d8%a7\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/harborlondon.com\/ar\/"},{"@type":"ListItem","position":2,"name":"\u0623\u0646\u0648\u0627\u0639 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629 \u0648\u0639\u0644\u0627\u062c\u0647\u0627"}]},{"@type":"WebSite","@id":"https:\/\/harborlondon.com\/ar\/#website","url":"https:\/\/harborlondon.com\/ar\/","name":"Harbor London","description":"Empathy in every stride. Expertise in every solution.","publisher":{"@id":"https:\/\/harborlondon.com\/ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/harborlondon.com\/ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/harborlondon.com\/ar\/#organization","name":"Harbor London","url":"https:\/\/harborlondon.com\/ar\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/harborlondon.com\/ar\/#\/schema\/logo\/image\/","url":"https:\/\/harborlondon.com\/wp-content\/uploads\/2025\/12\/favicon.png.webp","contentUrl":"https:\/\/harborlondon.com\/wp-content\/uploads\/2025\/12\/favicon.png.webp","width":264,"height":264,"caption":"Harbor London"},"image":{"@id":"https:\/\/harborlondon.com\/ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HarborLondon\/","https:\/\/www.linkedin.com\/company\/harborlondon\/","https:\/\/www.instagram.com\/harbor_london\/"]},{"@type":"Person","@id":"https:\/\/harborlondon.com\/ar\/#\/schema\/person\/c2669c495d1f1da3688092faf68af41f","name":"Dr. Farrukh Alam","image":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/secure.gravatar.com\/avatar\/5a609088fcc45c198040570c8f43a4c24eef5d0b7923a4b0942d193bb225dc9c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5a609088fcc45c198040570c8f43a4c24eef5d0b7923a4b0942d193bb225dc9c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5a609088fcc45c198040570c8f43a4c24eef5d0b7923a4b0942d193bb225dc9c?s=96&d=mm&r=g","caption":"Dr. Farrukh Alam"},"url":"https:\/\/harborlondon.com\/ar\/author\/dr-farrukh-alam\/"}]}},"taxonomy_info":{"category":[{"value":119,"label":"\u0627\u0644\u0623\u0645\u0631\u0627\u0636 \u0627\u0644\u0646\u0641\u0633\u064a\u0629"}],"post_tag":[{"value":227,"label":"\u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628 \u0627\u0644\u0646\u0641\u0633\u064a \u0648\u0639\u0644\u0627\u062c\u0647"},{"value":228,"label":"\u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629 \u0648\u0639\u0644\u0627\u062c\u0647\u0627"},{"value":229,"label":"\u0627\u0646\u0648\u0627\u0639 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629"}]},"featured_image_src_large":["https:\/\/harborlondon.com\/wp-content\/uploads\/2026\/01\/\u0627\u0644\u0646\u0641\u0633\u064a\u0629-scaled-1-1024x683.jpg",1024,683,true],"author_info":{"display_name":"\u062f. \u0641\u0627\u0631\u0648\u0642 \u0639\u0644\u0627\u0645","author_link":"https:\/\/harborlondon.com\/ar\/author\/dr-farrukh-alam\/"},"comment_info":"","category_info":[{"term_id":119,"name":"\u0627\u0644\u0623\u0645\u0631\u0627\u0636 \u0627\u0644\u0646\u0641\u0633\u064a\u0629","slug":"%d8%a7%d9%84%d8%a3%d9%85%d8%b1%d8%a7%d8%b6-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9","term_group":0,"term_taxonomy_id":119,"taxonomy":"category","description":"","parent":0,"count":18,"filter":"raw","cat_ID":119,"category_count":18,"category_description":"","cat_name":"\u0627\u0644\u0623\u0645\u0631\u0627\u0636 \u0627\u0644\u0646\u0641\u0633\u064a\u0629","category_nicename":"%d8%a7%d9%84%d8%a3%d9%85%d8%b1%d8%a7%d8%b6-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9","category_parent":0}],"tag_info":[{"term_id":227,"name":"\u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628 \u0627\u0644\u0646\u0641\u0633\u064a \u0648\u0639\u0644\u0627\u062c\u0647","slug":"%d8%a7%d9%84%d8%a7%d8%b6%d8%b7%d8%b1%d8%a7%d8%a8-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a-%d9%88%d8%b9%d9%84%d8%a7%d8%ac%d9%87","term_group":0,"term_taxonomy_id":227,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw"},{"term_id":228,"name":"\u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629 \u0648\u0639\u0644\u0627\u062c\u0647\u0627","slug":"%d8%a7%d9%84%d8%a7%d8%b6%d8%b7%d8%b1%d8%a7%d8%a8%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9-%d9%88%d8%b9%d9%84%d8%a7%d8%ac%d9%87%d8%a7","term_group":0,"term_taxonomy_id":228,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw"},{"term_id":229,"name":"\u0627\u0646\u0648\u0627\u0639 \u0627\u0644\u0627\u0636\u0637\u0631\u0627\u0628\u0627\u062a \u0627\u0644\u0646\u0641\u0633\u064a\u0629","slug":"%d8%a7%d9%86%d9%88%d8%a7%d8%b9-%d8%a7%d9%84%d8%a7%d8%b6%d8%b7%d8%b1%d8%a7%d8%a8%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%b3%d9%8a%d8%a9","term_group":0,"term_taxonomy_id":229,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw"}],"_links":{"self":[{"href":"https:\/\/harborlondon.com\/ar\/wp-json\/wp\/v2\/posts\/4674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/harborlondon.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/harborlondon.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/harborlondon.com\/ar\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/harborlondon.com\/ar\/wp-json\/wp\/v2\/comments?post=4674"}],"version-history":[{"count":4,"href":"https:\/\/harborlondon.com\/ar\/wp-json\/wp\/v2\/posts\/4674\/revisions"}],"predecessor-version":[{"id":4682,"href":"https:\/\/harborlondon.com\/ar\/wp-json\/wp\/v2\/posts\/4674\/revisions\/4682"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/harborlondon.com\/ar\/wp-json\/wp\/v2\/media\/4675"}],"wp:attachment":[{"href":"https:\/\/harborlondon.com\/ar\/wp-json\/wp\/v2\/media?parent=4674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/harborlondon.com\/ar\/wp-json\/wp\/v2\/categories?post=4674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/harborlondon.com\/ar\/wp-json\/wp\/v2\/tags?post=4674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}